{"id":1274,"date":"2023-05-15T10:23:24","date_gmt":"2023-05-15T15:23:24","guid":{"rendered":"https:\/\/dev.intermetperu.com\/?p=1274"},"modified":"2023-05-26T11:35:50","modified_gmt":"2023-05-26T16:35:50","slug":"34-plantas-de-oro-usando-metsim","status":"publish","type":"post","link":"https:\/\/intermetperu.com\/en\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/","title":{"rendered":"PLANTAS DE ORO USANDO METSIM\u00ae"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1274\" class=\"elementor elementor-1274\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-e5f90c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"59604\" data-id=\"e5f90c7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-c95580f\" data-eae-slider=\"96997\" data-id=\"c95580f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-def1da9 elementor-widget elementor-widget-text-editor\" data-id=\"def1da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"margin: 0px 0px 20px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; line-height: normal;\">PLANTAS DE ORO USANDO METSIM\u00ae<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c618c5 elementor-widget elementor-widget-image\" data-id=\"1c618c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"921\" src=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1.jpg\" class=\"attachment-full size-full wp-image-853\" alt=\"optimizacion-en-plantas-de-flotacion\" srcset=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1.jpg 2000w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1-300x138.jpg 300w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1-1024x472.jpg 1024w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1-768x354.jpg 768w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1-1536x707.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-697fe76 elementor-widget elementor-widget-text-editor\" data-id=\"697fe76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><h4><b>INTRODUCCI\u00d3N<\/b><\/h4><p>El procesamiento de los minerales aur\u00edferos ha constituido siempre un reto en la miner\u00eda. Las diferentes formas mineral\u00f3gicas de las menas acompa\u00f1antes del oro han complicado en cierta manera los procesos extractivos de este metal valioso. Sin embargo, el estudio y la capacitaci\u00f3n de las personas que tienen que ver con su procesamiento han permitido afrontar con \u00e9xito el tratamiento de menas aur\u00edferas.<\/p><p>El curso proporciona una visi\u00f3n general de las tecnolog\u00edas actuales de procesamiento y las t\u00e9cnicas para pruebas de lixiviaci\u00f3n de minerales aur\u00edferos y la interpretaci\u00f3n de sus resultados.<\/p><p>El objetivo es aplicarlas para obtener los m\u00e1ximos grados de extracci\u00f3n de oro desde los minerales. Los participantes dispondr\u00e1n de las herramientas necesarias para identificar t\u00e9cnicas de procesamiento, aplicarlas e interpretar resultados metal\u00fargicos involucrados en el procesamiento de menas aur\u00edferas.<\/p><p>\u00a0<\/p><h4><b>OBJETIVOS<\/b><\/h4><ul><li>Aplicar las t\u00e9cnicas adecuadas a menas aur\u00edferas, de acuerdo con las caracter\u00edsticas propias del mineral.<\/li><li>Reconocer los fundamentos b\u00e1sicos en el procesamiento de minerales aur\u00edferos.<\/li><li>Evaluar e interpretar las principales variables que influyen en los procesos extractivos del oro.<\/li><li>Ejecutar pruebas metal\u00fargicas de lixiviaci\u00f3n a fin de estimar extracciones de oro y consumo de reactivos.<\/li><li>Ejecutar balances de materia en los procesos de lixiviaci\u00f3n.<\/li><li>Planificar secuencias para la purificaci\u00f3n de un dor\u00e9 mediante la refinaci\u00f3n qu\u00edmica.<\/li><\/ul><h4><b>TOPICS<\/b><\/h4><ul><li>An\u00e1lisis integral de los yacimientos de oro y plata Mineralog\u00eda general y descriptiva del oro.<\/li><li>Concentraci\u00f3n de minerales aur\u00edferos Concentraci\u00f3n por gravimetr\u00eda Fundamentos te\u00f3ricos y tipos de separaci\u00f3n gravim\u00e9trica Clases de concentradores gravim\u00e9tricos y aplicaciones industriales Pruebas gravim\u00e9tricas en laboratorio y planta piloto.<\/li><li>Flotaci\u00f3n de minerales aur\u00edferos Fundamentos y mecanismo de la flotaci\u00f3n y su cin\u00e9tica Fundamentos operativos de la flotaci\u00f3n de minerales aur\u00edferos Pruebas experimentales y pilotos de flotaci\u00f3n aur\u00edfera Clases de celdas de flotaci\u00f3n y aplicaciones industriales aur\u00edferas.<\/li><li>Hidrometalurgia del oro Fundamentos de la cianuraci\u00f3n del oro y variables de operaci\u00f3n Termodin\u00e1mica y cin\u00e9tica de cianuraci\u00f3n del oro Cianuraci\u00f3n por percolaci\u00f3n Heap leaching integral del oro(CIC-CILO-PAL) y aglomeraci\u00f3n Par\u00e1metros de operaci\u00f3n y balances metal\u00fargicos Plantas aur\u00edferas industriales por percolaci\u00f3n Cianuraci\u00f3n por agitaci\u00f3n Procesos CIP-CIL &#8211; cianuraci\u00f3n convencional &#8211; SART-cianuraci\u00f3n intensiva Par\u00e1metros de operaci\u00f3n y balances metal\u00fargicos Laboratorio Metal\u00fargico y Plantas Industriales Tratamiento de minerales refractarios aur\u00edferos.<\/li><li>Procesos de recuperaci\u00f3n del oro Proceso Merrill crowe Procesos con Carb\u00f3n activado &#8211; Plantas ADR Proceso con resinas org\u00e1nicas &#8211; Plantas RIP-RIS y ADR Procesos de electrodeposici\u00f3n Plantas industriales con procesos de recuperaci\u00f3n del oro.<\/li><li>Pirometalurgia del oro Fundamentos te\u00f3ricos y operativos de la fundici\u00f3n del oro -escorias Fundentes y composiciones del flux para fusion del oro &#8211; balances Hornos de fundici\u00f3n y Retortas Fundamentos te\u00f3ricos y pr\u00e1cticos de la destilaci\u00f3n del Hg Plantas industriales con fundiciones de oro.<\/li><li>Refinaci\u00f3n qu\u00edmica y electrol\u00edtica del oro Refinaci\u00f3n qu\u00edmica del oro Refinaci\u00f3n con \u00e1cido n\u00edtrico y con agua regia Refinaci\u00f3n electrol\u00edtica del oro Refinaci\u00f3n qu\u00edmica de la plata Refinaci\u00f3n electrol\u00edtica de la plata Aplicaciones industriales de la refinaci\u00f3n del oro Tratamientos ambientales de efluentes residuales de plantas y minas.<\/li><\/ul><h4><b>PROGRAMA METSIM<\/b><\/h4><p>METSIM es un software de simulaci\u00f3n para plantas de procesamiento de minerales usado en la industria minera y metal\u00fargica. Cuenta con una amplia variedad de m\u00f3dulos que permiten simular plantas completas de extracci\u00f3n y producci\u00f3n de metales con un solo software. Se trata, por lo tanto, de un programa muy completo que permite adem\u00e1s realizar simulaciones tanto est\u00e1ticas como din\u00e1micas.<\/p><p>METSIM se origin\u00f3 como un programa de simulaci\u00f3n de procesos metal\u00fargicos, escrito para realizar balances masivos en torno a las principales operaciones unitarias de los diagramas de flujo de procesos complejos. La aplicaci\u00f3n del programa fue tan exitosa que se ampli\u00f3 para incluir balances t\u00e9rmicos detallados, qu\u00edmica, controles de procesos, dimensionamiento de equipos, estimaci\u00f3n de costos y an\u00e1lisis de procesos. La naturaleza \u00fanica del lenguaje de programaci\u00f3n, APL, permite la modificaci\u00f3n y expansi\u00f3n del sistema con el m\u00ednimo esfuerzo y permite la incorporaci\u00f3n de innovaciones tecnol\u00f3gicas continuas en la simulaci\u00f3n de procesos.<\/p><p>Se usar\u00e1 la versi\u00f3n 2018.06 actualizada del software METSIM \u00ae.<\/p><p>\u00a0<\/p><h4><b>CASOS PRACTICOS A DESARROLLAR<\/b><\/h4><ul><li>Circuito completo de lixiviaci\u00f3n con cianuro de un mineral de oro y plata en tanques por agitaci\u00f3n, lavado en CCD , merrill crowe ,retorta de mercurio y fundici\u00f3n con modelamiento de tanque de preparaci\u00f3n de cianuro y control de pH de la planta QW234.<\/li><li>Circuito 2 tanques CIL y 4 tanques CIP en serie para recuperaci\u00f3n de oro con carb\u00f3n activado en contracorriente de la planta HJ456.<\/li><li>Circuito de lixiviaci\u00f3n de oro con 3 tanques CIP y con carb\u00f3n activado en la planta concentradora SD891.<\/li><li>Modelamiento de pila de lixiviaci\u00f3n : Heap leaching de oro y recuperaci\u00f3n con una planta ADR de la unidad concentradora AS872.<\/li><\/ul><h4><b>INSTRUCTOR<\/b><\/h4><h5>Ing. CARLOS DE LA TORRE VIVAR<\/h5><p>Ingeniero Qu\u00edmico, con m\u00e1s de 15 a\u00f1os de experiencia profesional. Graduado de las Facultades de Qu\u00edmica e Ingenier\u00eda Qu\u00edmica de las universidades Cat\u00f3lica y de Ingenier\u00eda (Lima, Per\u00fa) respectivamente. Mag\u00edster en Qu\u00edmica (PUCP) y Mag\u00edster en Ingenier\u00eda Qu\u00edmica (UNI).y actualmente haciendo estudios de doctorado en Ingenier\u00eda Qu\u00edmica. Asimismo ha seguido diferentes cursos que complementan y actualizan sus conocimientos te\u00f3rico-pr\u00e1cticos en la materia.<\/p><p>Conocimientos de electr\u00f3nica digital y computaci\u00f3n. Amplios conocimientos de Software de Simulaci\u00f3n: Super Prodesigner, Chemcad, Aspen Plus, Hisys,Mathlab, Simulink, Modsim, LIMM , JKSimmet , Software de Aplicaci\u00f3n: Microsoft Office XP, Auto Cad, Lenguaje C, Visual Basic, Pascal, Corel, flash, PhotoShop, etc.<\/p><p>Amplia experiencia como Leader de dise\u00f1o de procesos mineros e industriales, habiendo desarrollado y dirigido los dise\u00f1os en su especialidad para los proyectos ejecutados por las compa\u00f1\u00edas mineras: Antamina, Buenaventura, El Brocal, Shougang, entre otras. Experiencia en instrumentaci\u00f3n qu\u00edmica y desarrollo de proyectos. Analista qu\u00edmico con experiencia en procesos industriales de fabricaci\u00f3n de cal, cemento, ladrillos, morteros, concreto; as\u00ed como procesos metal\u00fargicos en aspectos relevantes a dise\u00f1o de procesos, control de calidad, combusti\u00f3n, an\u00e1lisis de materias primas y mezclas. Conocimiento pr\u00e1ctico de la gesti\u00f3n de proyectos bajo el PMP (Project Management Professional), especialmente en proyectos minero metal\u00fargico.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c3912fb\" data-eae-slider=\"21642\" data-id=\"c3912fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9bfe3e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c9bfe3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pagolink.niubiz.com.pe\/pagoseguro\/INTERMET\/915294\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1 PAGAR AHORA !<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9048dd elementor-widget elementor-widget-text-editor\" data-id=\"f9048dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><b>PRECIO : US$240<\/b><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc1e5f9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fc1e5f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55f07f9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"55f07f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/intermetperu.com\/cursos-digitales\/index.php\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver a P\u00e1gina de Inicio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-110cee0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"110cee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5c24ce elementor-widget elementor-widget-heading\" data-id=\"e5c24ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 class=\"tituloblanco\" style=\"font-family: Oswald, Arial, sans-serif;font-size: 16px;margin: 6px;letter-spacing: 0.01em;white-space: normal\"><b>CONSULTA SOBRE ESTE CURSO<\/b><\/h2><p class=\"txtblanco\" style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px;white-space: normal\">No dude en comunicarce con nosotros y de inmediato lo vamos a guiar en todo lo necesario.<\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><textarea name=\"comentarios\" id=\"comentarios\" class=\"comentarios\" style=\"width: 242.135px;height: 100px;padding: 20px;border-width: 2px;border-radius: 0.25rem\"><\/textarea><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\">NOTA : Los campos que poseen (*) son considerados obligatorios.<\/p><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-f8ca08e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"30228\" data-id=\"f8ca08e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd8b52b\" data-eae-slider=\"34339\" data-id=\"cd8b52b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>PLANTAS DE ORO USANDO METSIM\u00ae \u00a0 INTRODUCCI\u00d3N El procesamiento de los minerales aur\u00edferos ha constituido siempre un reto en la miner\u00eda. Las diferentes formas mineral\u00f3gicas de las menas acompa\u00f1antes del oro han complicado en cierta manera los procesos extractivos de este metal valioso. Sin embargo, el estudio y la capacitaci\u00f3n de las personas que tienen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1274","post","type-post","status-publish","format-standard","hentry","category-cursos-digitales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PLANTAS DE ORO USANDO METSIM\u00ae - Intermetperu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PLANTAS DE ORO USANDO METSIM\u00ae - Intermetperu\" \/>\n<meta property=\"og:description\" content=\"PLANTAS DE ORO USANDO METSIM\u00ae \u00a0 INTRODUCCI\u00d3N El procesamiento de los minerales aur\u00edferos ha constituido siempre un reto en la miner\u00eda. Las diferentes formas mineral\u00f3gicas de las menas acompa\u00f1antes del oro han complicado en cierta manera los procesos extractivos de este metal valioso. Sin embargo, el estudio y la capacitaci\u00f3n de las personas que tienen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermetperu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-15T15:23:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-26T16:35:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/person\\\/6e69e73c2288d470ce4773feb0166e49\"},\"headline\":\"PLANTAS DE ORO USANDO METSIM\u00ae\",\"datePublished\":\"2023-05-15T15:23:24+00:00\",\"dateModified\":\"2023-05-26T16:35:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/\"},\"wordCount\":1174,\"publisher\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dev.intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/optimizacion-en-plantas-de-flotacion-1.jpg\",\"articleSection\":[\"cursos-digitales\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/\",\"name\":\"PLANTAS DE ORO USANDO METSIM\u00ae - Intermetperu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dev.intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/optimizacion-en-plantas-de-flotacion-1.jpg\",\"datePublished\":\"2023-05-15T15:23:24+00:00\",\"dateModified\":\"2023-05-26T16:35:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/#primaryimage\",\"url\":\"http:\\\/\\\/dev.intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/optimizacion-en-plantas-de-flotacion-1.jpg\",\"contentUrl\":\"http:\\\/\\\/dev.intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/optimizacion-en-plantas-de-flotacion-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/34-plantas-de-oro-usando-metsim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/intermetperu.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PLANTAS DE ORO USANDO METSIM\u00ae\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#website\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/\",\"name\":\"Intermetperu\",\"description\":\"intermeteperu\",\"publisher\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intermetperu.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\",\"name\":\"Intermetperu\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/INTERMET-LOGO.png\",\"contentUrl\":\"https:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/INTERMET-LOGO.png\",\"width\":3508,\"height\":1188,\"caption\":\"Intermetperu\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InterMetPeru\\\/?locale=es_LA\",\"https:\\\/\\\/www.instagram.com\\\/intermet_peru\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/person\\\/6e69e73c2288d470ce4773feb0166e49\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PLANTAS DE ORO USANDO METSIM\u00ae - Intermetperu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermetperu.com\/en\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/","og_locale":"en_US","og_type":"article","og_title":"PLANTAS DE ORO USANDO METSIM\u00ae - Intermetperu","og_description":"PLANTAS DE ORO USANDO METSIM\u00ae \u00a0 INTRODUCCI\u00d3N El procesamiento de los minerales aur\u00edferos ha constituido siempre un reto en la miner\u00eda. Las diferentes formas mineral\u00f3gicas de las menas acompa\u00f1antes del oro han complicado en cierta manera los procesos extractivos de este metal valioso. Sin embargo, el estudio y la capacitaci\u00f3n de las personas que tienen [&hellip;]","og_url":"https:\/\/intermetperu.com\/en\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/","og_site_name":"Intermetperu","article_publisher":"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","article_published_time":"2023-05-15T15:23:24+00:00","article_modified_time":"2023-05-26T16:35:50+00:00","og_image":[{"url":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/#article","isPartOf":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/"},"author":{"name":"admin","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49"},"headline":"PLANTAS DE ORO USANDO METSIM\u00ae","datePublished":"2023-05-15T15:23:24+00:00","dateModified":"2023-05-26T16:35:50+00:00","mainEntityOfPage":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/"},"wordCount":1174,"publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"image":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/#primaryimage"},"thumbnailUrl":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1.jpg","articleSection":["cursos-digitales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/","url":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/","name":"PLANTAS DE ORO USANDO METSIM\u00ae - Intermetperu","isPartOf":{"@id":"https:\/\/intermetperu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/#primaryimage"},"image":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/#primaryimage"},"thumbnailUrl":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1.jpg","datePublished":"2023-05-15T15:23:24+00:00","dateModified":"2023-05-26T16:35:50+00:00","breadcrumb":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/#primaryimage","url":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1.jpg","contentUrl":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/optimizacion-en-plantas-de-flotacion-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/intermetperu.com\/cursos-digitales\/34-plantas-de-oro-usando-metsim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/intermetperu.com\/"},{"@type":"ListItem","position":2,"name":"PLANTAS DE ORO USANDO METSIM\u00ae"}]},{"@type":"WebSite","@id":"https:\/\/intermetperu.com\/#website","url":"https:\/\/intermetperu.com\/","name":"Intermetperu","description":"intermeteperu","publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermetperu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/intermetperu.com\/#organization","name":"Intermetperu","url":"https:\/\/intermetperu.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/","url":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","contentUrl":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","width":3508,"height":1188,"caption":"Intermetperu"},"image":{"@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","https:\/\/www.instagram.com\/intermet_peru\/?hl=en"]},{"@type":"Person","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/intermetperu.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/1274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/comments?post=1274"}],"version-history":[{"count":0,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/1274\/revisions"}],"wp:attachment":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/media?parent=1274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/categories?post=1274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/tags?post=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}