{"id":1355,"date":"2023-05-15T12:42:55","date_gmt":"2023-05-15T17:42:55","guid":{"rendered":"https:\/\/dev.intermetperu.com\/?p=1355"},"modified":"2024-12-03T17:37:03","modified_gmt":"2024-12-03T22:37:03","slug":"43-conminucion-2019","status":"publish","type":"post","link":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/","title":{"rendered":"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1355\" class=\"elementor elementor-1355\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-e5f90c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"52824\" data-id=\"e5f90c7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c95580f\" data-eae-slider=\"22742\" data-id=\"c95580f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-def1da9 elementor-widget elementor-widget-text-editor\" data-id=\"def1da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"margin: 0px 0px 20px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; line-height: normal;\">CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c618c5 elementor-widget elementor-widget-image\" data-id=\"1c618c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"921\" src=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2.jpg\" class=\"attachment-full size-full wp-image-1227\" alt=\"practicas-en-molienda (2)\" srcset=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2.jpg 2000w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2-300x138.jpg 300w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2-1024x472.jpg 1024w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2-768x354.jpg 768w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2-1536x707.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-697fe76 elementor-widget elementor-widget-text-editor\" data-id=\"697fe76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La conminuci\u00f3n es la tecnolog\u00eda de procesos m\u00e1s antigua, asimismo una de las m\u00e1s amplias, extensas y complejas. Es amplia, debido a la enorme cantidad de rocas y part\u00edculas que son reducidas anualmente para sostener a la poblaci\u00f3n mundial. Es extensa debido a la amplia gama de procesos en las que se realiza la conminuci\u00f3n. Y, es compleja por las diversas variables que afectan su performance. Existe un dicho antiguo que dice: realiza correctamente la conminuci\u00f3n y la concentraci\u00f3n se ocupar\u00e1 de s\u00ed misma. Esto puede sonar como una exageraci\u00f3n, pero el sentido es el correcto. La conminuci\u00f3n es muy importante en el Per\u00fa debido a la abundancia de menas que contienen minerales valiosos en grano finos.<\/p><p>Las reuniones peri\u00f3dicas realizadas para revisar la pr\u00e1ctica actual de conminuci\u00f3n y con miras hacia el futuro pueden ser muy variadas siempre y cuando los temas en discusi\u00f3n est\u00e9n relacionados, pero, a fin de que se haga una contribuci\u00f3n significativa a la tecnolog\u00eda de proceso, los trabajos presentados deber\u00e1n tener cierto foco en la pr\u00e1ctica de la tecnolog\u00eda de la conminuci\u00f3n.<\/p><p>Conminuci\u00f3n 2019, un evento joven y con el que se planea tener una serie de ellos, estar\u00e1 necesariamente restringido a una categor\u00eda limitada de temas. Los escritos estar\u00e1n orientados a la rotura de rocas gruesas, su progenie en los molinos SAG, de rocas \u201cpebbles\u201d m\u00e1s peque\u00f1as en HPGRs y de las part\u00edculas m\u00e1s finas en los molinos de bolas vibratorios y giratorios de varios tipos.<\/p><p>En Conminuci\u00f3n 2019, la clasificaci\u00f3n ser\u00e1 considerada como una etapa de suma importancia en los procesos de molienda fina. Dicha clasificaci\u00f3n ha sido manejada mucho mejor por ingenieros de molienda en seco que aquellos de molienda h\u00fameda ya que se puede obtener r\u00e1pidamente una carga circulante en la molienda seca y puede reducir la productividad. Por ejemplo, los ingenieros de producci\u00f3n de cemento han construido tres generaciones de clasificadores para circuitos de cemento y las cargas circulantes se han reducido de un m\u00faltiplo alto a un m\u00faltiplo bajo. Por lo contrario, la clasificaci\u00f3n h\u00fameda ha progresado lentamente, siendo entre los principales desarrollos, el clasificador de rastrillos de hace m\u00e1s de 100 a\u00f1os y el hidrocicl\u00f3n de hace m\u00e1s de 50 a\u00f1os.<\/p><p>Conminuci\u00f3n 2019 ser\u00e1 un foro para debates y nuevas ideas. El debate generado por las nuevas ideas de Ritter von Rittinger acerca de la relaci\u00f3n reducci\u00f3n de tama\u00f1o\/ energ\u00eda a mediados del siglo XIX fue el que dio inicio a nuestra comprensi\u00f3n acerca de la conminuci\u00f3n y esperamos que este encuentro contribuya a que el debate fluya. Todo aporte t\u00e9cnico de la industria metal\u00fargica mundial ser\u00e1 bienvenido en la Conferencia de Conminuci\u00f3n a realizarse en Lima este 30 y 31 de mayo. \u00a1Sean todos bienvenidos!.<\/p><h4><b>COMIT\u00c9 DIRECTIVO<\/b><\/h4><h5>JUAN VELARDE<\/h5><p>Superintendente de Procesos.<\/p><p>Minera Chinalco, Toromocho.<\/p><h5>JULIO PALOMINO<\/h5><p>Superintendente de Operaciones.<\/p><p>MMG Minera Las Bambas.<\/p><h5>MARCIAL MEDINA<\/h5><p>Gerente de Procesos.<\/p><p>HUDBAY PER\u00da.<\/p><h5>HYDER MAMANI<\/h5><p>Superintendente de Metalurgia.<\/p><p>GOLDFIELDS Minera Cerro Corona.<\/p><h5>DELBI MOLINA<\/h5><p>Superintendente de Procesos Planta.<\/p><p>Sociedad Minera El Brocal.<\/p><h5>MARCO FLORES<\/h5><p>Superintendente de Planta.<\/p><p>Fortuna Silver Minera Bateas.<\/p><h4><b>COMIT\u00c9 CONSULTIVO<\/b><\/h4><h5><b>Dr. ALBAN J. LYNCH<\/b><\/h5><h5>Consejero Principal de Conminuci\u00f3n 2019 &#8211; II Congreso Internacional de Conminuci\u00f3n de Minerales<\/h5><p>Alban Lynch culmin\u00f3 sus estudios de Ingenier\u00eda Qu\u00edmica en la Universidad T\u00e9cnica de S\u00eddney en 1953 luego de haber trabajado durante 6 a\u00f1os como t\u00e9cnico en pintura.<\/p><p>Luego, se mud\u00f3 a Broken Hill en donde culmin\u00f3 sus estudios de bachillerato, maestr\u00eda y doctorado en ciencias en la Universidad de Nueva Gales del Sur mientras trabajaba como ingeniero de procesamiento de minerales en Zinc Corporation (actualmente Rio Tinto). En 1961, se mud\u00f3 a la Universidad de Queensland como Ingeniero de investigaci\u00f3n, en donde AMIRA (Asociaci\u00f3n de Investigaci\u00f3n de la Industria de Minerales de Australia) le entreg\u00f3 una beca para trabajar en el modelamiento y control de circuitos de molienda. Su enfoque era trabajar con plantas en operaci\u00f3n como sus sitios de experimentaci\u00f3n para reunir datos que luego puedan utilizarse para la elaboraci\u00f3n del modelamiento y aumentarlos cuando fuera necesario por medio de la informaci\u00f3n de las perforaciones de prueba. Por ejemplo, los hidrociclones aparecieron en 1960 y reemplazaban a los clasificadores de rastrillo, de manera que se reun\u00eda datos generales de una perforaci\u00f3n de prueba de un cicl\u00f3n para elaborar un modelo de cicl\u00f3n.<\/p><p>Asimismo, se encontraba disponible un modelo simple de molino de bolas que permiti\u00f3 se modelara un molino de bolas y un cicl\u00f3n como circuito cerrado, y pudo ser utilizado para predecir qu\u00e9 es lo que ocurr\u00eda cuando se realizaba un cambio a las condiciones de operaci\u00f3n del circuito cerrado.<\/p><p>Los modelos que se utilizaron fueron un estimado, sin embargo, el valor de la t\u00e9cnica de simulaci\u00f3n fue clara y la investigaci\u00f3n continu\u00f3 en el desarrollo de m\u00e1s modelos precisos de molinos de molienda y clasificadores. Lo que se convirti\u00f3 en un proyecto de 50 a\u00f1os, bajo el firme respaldo por los procesadores de minerales Australianos. Actualmente, todos los trabajos de optimizaci\u00f3n y dise\u00f1o de planta usan simulaci\u00f3n.<\/p><p>Asimismo, Alban Lynch ha tomado inter\u00e9s en la historia del procesamiento de minerales. Entre sus libros sobre el procesamiento de minerales est\u00e1n la Historia de la Molienda (The History of Grinding), Historia de la Flotaci\u00f3n (The History of Flotation), Manual de Conminuci\u00f3n (Comminution Handbook) y libros sobre la simulaci\u00f3n de molienda de minerales y circuitos de flotaci\u00f3n. Dr. Lynch ha recibido variedad de premios tanto por el Instituto Australiano de Miner\u00eda y Metalurgia y, la Sociedad de Ingenieros de Minas.<\/p><h5><b>Dr. MALCOLM POWELL<\/b><\/h5><h5>Consultor Mundial en Optimizaci\u00f3n de Plantas Concentradoras<\/h5><p>Obtuvo su doctorado en la University of Cape Town. Actualmente es director y profesor en Conminuci\u00f3n sustentable en el JKMRC de la Universidad de Queensland.Es invitado frecuente en las m\u00e1s importantes conferencias del mundo realizando presentaciones sobre investigaci\u00f3n aplicada en circuitos flexibles, modelamiento y control en molienda y es conocido por sus innumerables consultor\u00edas y servicios a la Industria minera.<\/p><p>Ha sido presidente de Conminuci\u00f3n 2017 realizado en Lima y organizado por InterMet.<\/p><h4><b>PROGRAMA<\/b><\/h4><h5>SESION I<\/h5><ul><li>Optimizaci\u00f3n integrada del rendimiento de los circuitos de conminuci\u00f3n. Malcolm Powell. JKMRC Universidad de Queensland. Australia.<\/li><li>IsaMill &#8211; 25 a\u00f1os de Molienda Agitada. Hans De Waal. Glencore Technology. Australia.<\/li><\/ul><h5>SESION II<\/h5><ul><li>4 generaciones de conos de trituraci\u00f3n- necesidades del siglo XXI. Dave Mc Cracken. Astec Aggregate &amp; Mining Group. USA.<\/li><li>Aprovechando una tecnolog\u00eda \u00fanica e innovadora de medici\u00f3n de tama\u00f1o de part\u00edcula en una concentradora de cobre: transformar la informaci\u00f3n en conocimiento. John Viega. Cidra Minerals. USA.<\/li><li>Aplicaci\u00f3n del Vertimills \u2122 en circuitos de molienda primaria.Luis Chia. Metso. Per\u00fa.<\/li><\/ul><h5>SESION III<\/h5><ul><li>Alternativas del dise\u00f1o de conminuci\u00f3n: un compromiso entre las alternativas de reducci\u00f3n de tama\u00f1o. Tugcan Tuzcu. DAMA Engineering. Turqu\u00eda.<\/li><li>Impactos de la transici\u00f3n Turbulento\/Laminar en el transporte de pulpa en Circuitos de Conminuci\u00f3n &#8211; experiencia en Caserones. Oscar Castro. FLSmidth. Chile.<\/li><li>Implementaci\u00f3n de Molienda Fina en una planta de procesamiento de oro. Mattias Astholm. Outotec.<\/li><li>Determinaci\u00f3n de las constantes cin\u00e9ticas de molienda (funci\u00f3n selecci\u00f3n y fractura) a trav\u00e9s de un algoritmo de programaci\u00f3n matricial. Ernesto Vizcardo. Aceros Chilca. Minera Shougang. Per\u00fa.<\/li><\/ul><h5>SESION IV<\/h5><ul><li>Estimaci\u00f3n de la distribuci\u00f3n de tama\u00f1os ROM y SAG mediante simulaci\u00f3n inversa. Jorge Menacho. De Remetalica. Chile.<\/li><li>Impacto de la voladura en procesos aguas abajo para maximizar la rentabilidad de las industrias mineras. Andrea Lucero. Per\u00fa.<\/li><li>Miner\u00eda Digital. Jeffrey Dawes. Komatsu Mining Corp. USA.<\/li><\/ul><h5>SESION V<\/h5><ul><li>Optimizaci\u00f3n de los circuitos de molienda y clasificaci\u00f3n para el tratamiento de minerales de cobre y polimet\u00e1licos. Rodrigo Rosales. LJM Metales. Per\u00fa.<\/li><li>Hallazgos de investigaci\u00f3n que conducen a nuevos dise\u00f1os en banana screens. Kennth Mayhew. Vicente Esparza. Derrick Alston\/ Inter Mining Process. Sud\u00e1frica.<\/li><li>Dise\u00f1o y Operaci\u00f3n de Circuitos de Molienda en CODELCO. Jaime D\u00edaz Catal\u00e1n. Codelco. Chile.<\/li><\/ul><h5>SESION VI<\/h5><ul><li>Control del nivel de bolas en Molino SAG por realidad aumentada en Cerro Corona. Christian Huaira. GoldFields Minera Cerro Corona. Per\u00fa.<\/li><li>Estudio de la din\u00e1mica de desgaste en molinos VTM utilizando herramientas l\u00e1ser 3D.Rudy Jaramillo. Magotteaux. Per\u00fa.<\/li><li>Control de Nivel de Carga en Molino SAG para la Reducci\u00f3n del Taponamiento de parrillas.Humberto Villanueva. Iv\u00e1n Poma. Toromocho Minera Chinalco.<\/li><\/ul><h5>SESION VII<\/h5><ul><li>Inyecci\u00f3n de agua de lavado en hidrociclones para mejorar la calidad del underflow en la presa de almacenamiento de relaves. Pablo Hinojosa. UNSA. Per\u00fa.<\/li><li>Modelamiento y Simulaci\u00f3n de un Circuito abierto HPGR para una Planta de p\u00f3rfidos de cobre. Miguel Mayta. UNSA. Per\u00fa.<\/li><li>Optimizaci\u00f3n del proceso en la Planta Concentradora Bateas. Marco Flores. Minera Bateas. Per\u00fa.<\/li><li>\u00bfC\u00f3mo dimensionar en forma \u00f3ptima un circuito de molienda SAG a partir de las pruebas piloto y los par\u00e1metros de dureza de la geometalurgia?. Cristian Riquelme. Chile.<\/li><\/ul><h5>SESION VIII<\/h5><ul><li>Optimizaci\u00f3n del tama\u00f1o de bola en Molienda SAG mediante el uso de simulaciones de m\u00e9todos discretos. C\u00e9sar Poma. Levi Guzm\u00e1n. MolyCop.<\/li><li>Estimaci\u00f3n del work \u00edndex por correlaciones estad\u00edsticas por el m\u00e9todo de Chakrabarti. Fredy Zegarra. Ernesto Vizcardo. Minera Shougang. Aceros Chilca. Per\u00fa.<\/li><li>Nuevos impulsos para mejores pr\u00e1cticas geometal\u00fargicas. Jorge Menacho. De Remet\u00e1lica. Chile.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8cf7bef\" data-eae-slider=\"73551\" data-id=\"8cf7bef\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-919b0b3 elementor-widget elementor-widget-heading\" data-id=\"919b0b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INVERSI\u00d3N USD 240<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0b2579 elementor-widget elementor-widget-heading\" data-id=\"d0b2579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo acceder al curso?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd4803f elementor-widget elementor-widget-text-editor\" data-id=\"bd4803f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paso 1:<\/strong><\/p><p>Realiza el pago Web<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2071db elementor-widget elementor-widget-button\" data-id=\"b2071db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pagolink.niubiz.com.pe\/pagoseguro\/INTERMET\/915406\/info\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-credit-card\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar USD 240<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdf7898 elementor-widget elementor-widget-text-editor\" data-id=\"cdf7898\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paso 2:<\/strong><\/p><p>Completa el formulario y adjunta tu comprobante<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88df89e elementor-widget elementor-widget-button\" data-id=\"88df89e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/form.jotform.com\/243266023544654\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-wpforms\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Registra tu pago<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f28d6f elementor-widget elementor-widget-text-editor\" data-id=\"3f28d6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paso 3:<\/strong><\/p><p>Procederemos a enviarte un correo con tus accesos a nuestro Campus Virtual.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-763bf38 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"763bf38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5063c43 elementor-widget elementor-widget-heading\" data-id=\"5063c43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Si tienes alguna consulta, escr\u00edbenos:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51e98ce elementor-align-center elementor-widget elementor-widget-button\" data-id=\"51e98ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/wa.link\/nqku2f\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ATENCI\u00d3N AL CLIENTE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8936d71 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8936d71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b474f6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b474f6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-f8ca08e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"61291\" data-id=\"f8ca08e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd8b52b\" data-eae-slider=\"2098\" data-id=\"cd8b52b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES La conminuci\u00f3n es la tecnolog\u00eda de procesos m\u00e1s antigua, asimismo una de las m\u00e1s amplias, extensas y complejas. Es amplia, debido a la enorme cantidad de rocas y part\u00edculas que son reducidas anualmente para sostener a la poblaci\u00f3n mundial. Es extensa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1355","post","type-post","status-publish","format-standard","hentry","category-cursos-digitales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES - Intermetperu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES - Intermetperu\" \/>\n<meta property=\"og:description\" content=\"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES La conminuci\u00f3n es la tecnolog\u00eda de procesos m\u00e1s antigua, asimismo una de las m\u00e1s amplias, extensas y complejas. Es amplia, debido a la enorme cantidad de rocas y part\u00edculas que son reducidas anualmente para sostener a la poblaci\u00f3n mundial. Es extensa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermetperu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-15T17:42:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-03T22:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/person\\\/6e69e73c2288d470ce4773feb0166e49\"},\"headline\":\"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES\",\"datePublished\":\"2023-05-15T17:42:55+00:00\",\"dateModified\":\"2024-12-03T22:37:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/\"},\"wordCount\":1690,\"publisher\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/practicas-en-molienda-2.jpg\",\"articleSection\":[\"cursos-digitales\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/\",\"name\":\"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES - Intermetperu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/practicas-en-molienda-2.jpg\",\"datePublished\":\"2023-05-15T17:42:55+00:00\",\"dateModified\":\"2024-12-03T22:37:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/#primaryimage\",\"url\":\"http:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/practicas-en-molienda-2.jpg\",\"contentUrl\":\"http:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/practicas-en-molienda-2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/cursos-digitales\\\/43-conminucion-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/intermetperu.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#website\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/\",\"name\":\"Intermetperu\",\"description\":\"intermeteperu\",\"publisher\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intermetperu.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\",\"name\":\"Intermetperu\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/INTERMET-LOGO.png\",\"contentUrl\":\"https:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/INTERMET-LOGO.png\",\"width\":3508,\"height\":1188,\"caption\":\"Intermetperu\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InterMetPeru\\\/?locale=es_LA\",\"https:\\\/\\\/www.instagram.com\\\/intermet_peru\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/person\\\/6e69e73c2288d470ce4773feb0166e49\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES - Intermetperu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/","og_locale":"en_US","og_type":"article","og_title":"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES - Intermetperu","og_description":"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES La conminuci\u00f3n es la tecnolog\u00eda de procesos m\u00e1s antigua, asimismo una de las m\u00e1s amplias, extensas y complejas. Es amplia, debido a la enorme cantidad de rocas y part\u00edculas que son reducidas anualmente para sostener a la poblaci\u00f3n mundial. Es extensa [&hellip;]","og_url":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/","og_site_name":"Intermetperu","article_publisher":"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","article_published_time":"2023-05-15T17:42:55+00:00","article_modified_time":"2024-12-03T22:37:03+00:00","og_image":[{"url":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/#article","isPartOf":{"@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/"},"author":{"name":"admin","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49"},"headline":"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES","datePublished":"2023-05-15T17:42:55+00:00","dateModified":"2024-12-03T22:37:03+00:00","mainEntityOfPage":{"@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/"},"wordCount":1690,"publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"image":{"@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/#primaryimage"},"thumbnailUrl":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2.jpg","articleSection":["cursos-digitales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/","url":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/","name":"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES - Intermetperu","isPartOf":{"@id":"https:\/\/intermetperu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/#primaryimage"},"image":{"@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/#primaryimage"},"thumbnailUrl":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2.jpg","datePublished":"2023-05-15T17:42:55+00:00","dateModified":"2024-12-03T22:37:03+00:00","breadcrumb":{"@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/#primaryimage","url":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2.jpg","contentUrl":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/practicas-en-molienda-2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/intermetperu.com\/en\/cursos-digitales\/43-conminucion-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/intermetperu.com\/"},{"@type":"ListItem","position":2,"name":"CONMINUCI\u00d3N 2019 : I CONGRESO INTERNACIONAL ENFOCADO EN TRITURACI\u00d3N, MOLIENDA Y CLASIFICACI\u00d3N DE MINERALES"}]},{"@type":"WebSite","@id":"https:\/\/intermetperu.com\/#website","url":"https:\/\/intermetperu.com\/","name":"Intermetperu","description":"intermeteperu","publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermetperu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/intermetperu.com\/#organization","name":"Intermetperu","url":"https:\/\/intermetperu.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/","url":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","contentUrl":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","width":3508,"height":1188,"caption":"Intermetperu"},"image":{"@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","https:\/\/www.instagram.com\/intermet_peru\/?hl=en"]},{"@type":"Person","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/intermetperu.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/1355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/comments?post=1355"}],"version-history":[{"count":0,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/1355\/revisions"}],"wp:attachment":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/media?parent=1355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/categories?post=1355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/tags?post=1355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}