{"id":304,"date":"2023-05-03T11:54:52","date_gmt":"2023-05-03T16:54:52","guid":{"rendered":"https:\/\/dev.intermetperu.com\/?p=304"},"modified":"2023-06-07T15:35:38","modified_gmt":"2023-06-07T20:35:38","slug":"129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico","status":"publish","type":"post","link":"https:\/\/intermetperu.com\/en\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/","title":{"rendered":"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"304\" class=\"elementor elementor-304\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-e5f90c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"78580\" data-id=\"e5f90c7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-c95580f\" data-eae-slider=\"61509\" data-id=\"c95580f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2269594 elementor-widget elementor-widget-heading\" data-id=\"2269594\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c618c5 elementor-widget elementor-widget-image\" data-id=\"1c618c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"921\" src=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo.jpg\" class=\"attachment-full size-full wp-image-306\" alt=\"teoria-de-muestreo\" srcset=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo.jpg 2000w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo-300x138.jpg 300w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo-1024x472.jpg 1024w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo-768x354.jpg 768w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo-1536x707.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-697fe76 elementor-widget elementor-widget-text-editor\" data-id=\"697fe76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section><section><h4>\u00bfQU\u00c9 APRENDER\u00c1?<\/h4><ul><li>Hechos sorprendentes acerca de las consecuencias de un mal muestreo y las dificultades de un buen muestreo.<\/li><li>La amplitud inesperada de las ramificaciones econ\u00f3micas de un mal muestreo.<\/li><li>Saber c\u00f3mo se toman las muestras para obtener la alta ley de representatividad.<\/li><li>Controlar los requerimientos de la muestra de masa y evitar errores en el muestreo y en los protocolo de preparaci\u00f3n de las muestras.<\/li><li>C\u00f3mo eliminar los factores desfavorables<\/li><li>C\u00f3mo identificar aquellos factores desfavorables que no pueden ser eliminados pero pueden ser minimizados.<\/li><li>El significado y significancia de los factores utilizados en las f\u00f3rmulas de control num\u00e9ricas de la varianza del muestreo.<\/li><li>Los costos disponibles para la mejor personalizaci\u00f3n de los par\u00e1metros de control para el tipo de mineralizaci\u00f3n.<\/li><li>Lo que se puede y no se puede obtener con los experimentos del muestreo.<\/li><li>La filosof\u00eda general que resalta la buena pr\u00e1ctica del muestreo y el modelamiento de los par\u00e1metros del muestreo.<\/li><li>C\u00f3mo abordar los problemas de muestreo aparentemente intratables.<\/li><li>La diferencia entre el muestreo, la interpolaci\u00f3n y la extrapolaci\u00f3n.<\/li><\/ul><h4>P\u00daBLICO OBJETIVO<\/h4><p>El presente curso est\u00e1 dise\u00f1ado para aquellos profesionales responsables que se encargan en la optimizaci\u00f3n de las minas, plantas metal\u00fargicas, plantas qu\u00edmicas y los an\u00e1lisis ambientales. Asimismo, el curso est\u00e1 dirigido para otros profesionales involucrados en la toma de muestras para la toma de decisiones. Por \u00faltimo, este curso es altamente recomendando para gerentes que buscan optimizar sus operaciones. Recomendado para:<\/p><ul><li>Geologos de exploraci\u00f3n y control de ley del mineral<\/li><li>Jefe, Subjefe y gerente de operaciones<\/li><li>Geoestad\u00edsticos<\/li><li>Supervisores de laboratorio<\/li><li>Ingeniero de minas, metalurgistas, geometalurgistas o qu\u00edmicos<\/li><li>Gerentes de QA\/QC<\/li><li>Ingenieros ambientales, especialistas en el control de la contaminaci\u00f3n<\/li><li>Inversionistas, accionistas de empresas o banqueros interesados<\/li><\/ul><h4>TOPICS<\/h4><p>\u00a0<\/p><h5>D\u00cdA 1: LA NECESIDAD HIST\u00d3RICA DE LA TEOR\u00cdA DEL MUESTREO<\/h5><ul><li>Importancia del muestreo, incluido la econom\u00eda<\/li><li>Definiciones, terminolog\u00eda y casos pr\u00e1cticos<\/li><li>Recomendaciones generales a nivel pr\u00e1ctico<\/li><li>Pautas acerca de la masa de muestra necesaria<\/li><li>Evaluaci\u00f3n y control del factor de segregaci\u00f3n<\/li><li>Evaluaciones de heterogeneidad recomendadas<\/li><li>Dos leyes cardinales importantes para la optimizaci\u00f3n de la muestra de masa en los protocolos de muestreo<\/li><li>Elaboraci\u00f3n de tablas de muestreo (monogramas)<\/li><\/ul><h5>D\u00cdA 2 Y 3: MUESTREO, LEY DE CONTROL E INNOVACI\u00d3N DEL DESEMPE\u00d1O DE LAS PLANTAS PROCESADORAS<\/h5><ul><li>El muestreo \u00f3ptimo para las estimaciones de la reserve del mineral: todas las t\u00e9cnicas de perforaci\u00f3n son responsables del sesgo. La concientizaci\u00f3n de estos problemas es esencial para los comit\u00e9s que est\u00e1n a cargo de los estudios de viabilidad.<\/li><li>Los datos de perforaci\u00f3n de barrenos y los datos de la planta de muestra son fuentes ricas en informaci\u00f3n valiosa que est\u00e1n muy infravaloradas e infrautilizadas. Existen m\u00e9todos sencillos para crear este trabajo de informaci\u00f3n para mejorar su operaci\u00f3n, f\u00e1cil en aplicar el control de beneficio y desarrollo para sus operaciones metal\u00fargicas.<\/li><li>Muchas fuentes de sesgo afectan la perforaci\u00f3n de barrenos: la concientizaci\u00f3n de estos problemas pueden ayudar mucho en facilitar y optimizar los procesos mineros en general. Pasar por alto estos problemas encaminan perdidas financieras devastadoras a su empresa.<\/li><li>En Planta, el control de proceso para el muestreo no es muestreo para la contabilidad metal\u00fargica. Estos dos tipos de muestreo son incompatibles y opuestos al criterio de muchas personas en la industria. No se puede tener las dos maneras utilizando los mismos sistemas de muestreo al menos que disponga con la actual tecnolog\u00eda disponible a nivel mundial. Se ofrecen recomendaciones l\u00f3gicas.<\/li><li>Sistemas de muestreo apropiados para la contabilidad metal\u00fargica.<\/li><li>Sistemas de muestreo apropiados para la automatizaci\u00f3n del control de procesos: una necesidad absoluta en tiempo real.<\/li><\/ul><h4>FRANCIS F. PITARD<\/h4>Dr. Francis F. Pitard es consultor experto en Muestreo, Control del Proceso Estad\u00edstico (SPC) y Gesti\u00f3n de la Calidad Total (TQM). Pitard es presidente de Francis Pitard Sampling Consultants ubicado en Broomfield, Colorado, EE. UU. El Dr. Pitard tiene seis a\u00f1os de experiencia con la Comisi\u00f3n Francesa de Energ\u00eda At\u00f3mica y quince a\u00f1os en la Amax Etractive R&amp;D. Imparte clases acerca de la Teor\u00eda del Muestreo para las Oficinas de Educaci\u00f3n Continua de la Escuela de Minas de Colorado. Doctor en Tecnolog\u00edas de la Universidad Aalborg ubicado en Dinamarca y autor de la Teor\u00eda del Muestreo y de la Pr\u00e1ctica del Muestreo (3a Ed., 2019).<\/section><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c3912fb\" data-eae-slider=\"99176\" data-id=\"c3912fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9bfe3e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c9bfe3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pagolink.niubiz.com.pe\/pagoseguro\/INTERMET\/1243821\/info\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1 PAGAR AHORA !<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9048dd elementor-widget elementor-widget-text-editor\" data-id=\"f9048dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><b>PRECIO : US$ 1500<\/b><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc1e5f9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fc1e5f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-110cee0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"110cee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ccc0c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d6ccc0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO \u00bfQU\u00c9 APRENDER\u00c1? Hechos sorprendentes acerca de las consecuencias de un mal muestreo y las dificultades de un buen muestreo. La amplitud inesperada de las ramificaciones econ\u00f3micas de un mal muestreo. Saber c\u00f3mo se toman las muestras para obtener la alta ley de representatividad. Controlar los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[7],"tags":[],"class_list":["post-304","post","type-post","status-publish","format-standard","hentry","category-nuevos-cursos-digitales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO - Intermetperu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermetperu.com\/en\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO - Intermetperu\" \/>\n<meta property=\"og:description\" content=\"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO \u00bfQU\u00c9 APRENDER\u00c1? Hechos sorprendentes acerca de las consecuencias de un mal muestreo y las dificultades de un buen muestreo. La amplitud inesperada de las ramificaciones econ\u00f3micas de un mal muestreo. Saber c\u00f3mo se toman las muestras para obtener la alta ley de representatividad. Controlar los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermetperu.com\/en\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermetperu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-03T16:54:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-07T20:35:38+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/person\\\/6e69e73c2288d470ce4773feb0166e49\"},\"headline\":\"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO\",\"datePublished\":\"2023-05-03T16:54:52+00:00\",\"dateModified\":\"2023-06-07T20:35:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/\"},\"wordCount\":788,\"publisher\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dev.intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/teoria-de-muestreo.jpg\",\"articleSection\":[\"nuevos-cursos-digitales\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/\",\"name\":\"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO - Intermetperu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dev.intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/teoria-de-muestreo.jpg\",\"datePublished\":\"2023-05-03T16:54:52+00:00\",\"dateModified\":\"2023-06-07T20:35:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/#primaryimage\",\"url\":\"http:\\\/\\\/dev.intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/teoria-de-muestreo.jpg\",\"contentUrl\":\"http:\\\/\\\/dev.intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/teoria-de-muestreo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/nuevos-cursos-digitales\\\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/intermetperu.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#website\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/\",\"name\":\"Intermetperu\",\"description\":\"intermeteperu\",\"publisher\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intermetperu.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\",\"name\":\"Intermetperu\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/INTERMET-LOGO.png\",\"contentUrl\":\"https:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/INTERMET-LOGO.png\",\"width\":3508,\"height\":1188,\"caption\":\"Intermetperu\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InterMetPeru\\\/?locale=es_LA\",\"https:\\\/\\\/www.instagram.com\\\/intermet_peru\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/person\\\/6e69e73c2288d470ce4773feb0166e49\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO - Intermetperu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermetperu.com\/en\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/","og_locale":"en_US","og_type":"article","og_title":"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO - Intermetperu","og_description":"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO \u00bfQU\u00c9 APRENDER\u00c1? Hechos sorprendentes acerca de las consecuencias de un mal muestreo y las dificultades de un buen muestreo. La amplitud inesperada de las ramificaciones econ\u00f3micas de un mal muestreo. Saber c\u00f3mo se toman las muestras para obtener la alta ley de representatividad. Controlar los [&hellip;]","og_url":"https:\/\/intermetperu.com\/en\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/","og_site_name":"Intermetperu","article_publisher":"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","article_published_time":"2023-05-03T16:54:52+00:00","article_modified_time":"2023-06-07T20:35:38+00:00","og_image":[{"url":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/#article","isPartOf":{"@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/"},"author":{"name":"admin","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49"},"headline":"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO","datePublished":"2023-05-03T16:54:52+00:00","dateModified":"2023-06-07T20:35:38+00:00","mainEntityOfPage":{"@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/"},"wordCount":788,"publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"image":{"@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/#primaryimage"},"thumbnailUrl":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo.jpg","articleSection":["nuevos-cursos-digitales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/","url":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/","name":"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO - Intermetperu","isPartOf":{"@id":"https:\/\/intermetperu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/#primaryimage"},"image":{"@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/#primaryimage"},"thumbnailUrl":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo.jpg","datePublished":"2023-05-03T16:54:52+00:00","dateModified":"2023-06-07T20:35:38+00:00","breadcrumb":{"@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/#primaryimage","url":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo.jpg","contentUrl":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/teoria-de-muestreo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/intermetperu.com\/nuevos-cursos-digitales\/129-teoria-de-muestreo-practicas-de-muestreo-y-su-impacto-economico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/intermetperu.com\/"},{"@type":"ListItem","position":2,"name":"TEOR\u00cdA DE MUESTREO, PR\u00c1CTICAS DE MUESTREO Y SU IMPACTO ECON\u00d3MICO"}]},{"@type":"WebSite","@id":"https:\/\/intermetperu.com\/#website","url":"https:\/\/intermetperu.com\/","name":"Intermetperu","description":"intermeteperu","publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermetperu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/intermetperu.com\/#organization","name":"Intermetperu","url":"https:\/\/intermetperu.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/","url":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","contentUrl":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","width":3508,"height":1188,"caption":"Intermetperu"},"image":{"@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","https:\/\/www.instagram.com\/intermet_peru\/?hl=en"]},{"@type":"Person","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/intermetperu.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/comments?post=304"}],"version-history":[{"count":0,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/304\/revisions"}],"wp:attachment":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/media?parent=304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/categories?post=304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/tags?post=304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}