{"id":3316,"date":"2023-07-19T11:58:37","date_gmt":"2023-07-19T16:58:37","guid":{"rendered":"https:\/\/intermetperu.com\/?p=3316"},"modified":"2024-11-26T10:47:51","modified_gmt":"2024-11-26T15:47:51","slug":"52-primer-congreso-internacional-de-muestreo-de-minerales","status":"publish","type":"post","link":"https:\/\/intermetperu.com\/en\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/","title":{"rendered":"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3316\" class=\"elementor elementor-3316\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-e5f90c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"72090\" data-id=\"e5f90c7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c95580f\" data-eae-slider=\"50388\" data-id=\"c95580f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-def1da9 elementor-widget elementor-widget-text-editor\" data-id=\"def1da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"margin: 0px 0px 20px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; line-height: normal;\">I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c618c5 elementor-widget elementor-widget-image\" data-id=\"1c618c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"354\" src=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg\" class=\"attachment-medium_large size-medium_large wp-image-3307\" alt=\"optimizacion-en-plantas-de-flotacion (3)\" srcset=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg 768w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-300x138.jpg 300w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-1024x472.jpg 1024w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-1536x707.jpg 1536w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-697fe76 elementor-widget elementor-widget-text-editor\" data-id=\"697fe76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>PALABRAS DE BIENVENIDA<\/h4><p>La Teor\u00eda del Muestreo, como se presenta en los libros, no es un producto aceptable para ser usado por la industria. La mayor\u00eda de los profesionales en la industria no tienen el tiempo para dedicarse a profundidad en las sutilezas de la Teor\u00eda del Muestreo; ellos quieren ir directo al punto. El problema es que hay casos ilimitados sobre los cuales muchos libros pueden escribirse, sugiriendo que los ejecutivos no tienen idea de cuan costosa pueden ser las malas pr\u00e1cticas de muestreo. Este congreso de muestreo destaca \u00e1reas selectas en la industria minera y de procesamiento donde las buenas pr\u00e1cticas de muestreo son esenciales. A menos que la Teor\u00eda del Muestreo sea presentada en un contexto de Gesti\u00f3n Total de la Calidad, esta no puede y no cumplir\u00e1 su misi\u00f3n; este es un hecho abrumador que he observado personalmente por m\u00e1s de 40 a\u00f1os. Muchos ejemplos de industrias espec\u00edficas se han observado y ellos involucran grandes p\u00e9rdidas econ\u00f3micas si es que el conocimiento preventivo de la Teor\u00eda del Muestreo no es tomado en cuenta por los ejecutivos y sus equipos de administraci\u00f3n de negocios. El muestreo correcto es el n\u00facleo sustantivo de la Teor\u00eda del Muestreo, por tanto ejemplos de importancia cr\u00edtica deber\u00edan revisarse durante este congreso basado en la alta frecuencia de su repetici\u00f3n en su respectivo dominio de aplicaci\u00f3n. Un lugar importante se deber\u00eda dar al Efecto Pepita In Situ o \u201cIn Situ Nugget efect\u201d ya que este ha sido como el ni\u00f1o olvidado tanto por la Teor\u00eda del Muestreo como por la Geoestad\u00edstica. Un necesario trabajo dedicado al Efecto Pepita In Situ ha hecho falta desde hace tiempo con el fin de corregir esta deficiencia te\u00f3rica y pr\u00e1ctica, que trae unas impresionantes consecuencias econ\u00f3micas si no se le toma en cuenta. La toma de muestras en los barrenos o \u201cblastholes\u201d en la miner\u00eda a cielo abierto es responsable de las p\u00e9rdidas de dinero masivas alrededor del mundo cada a\u00f1o, por tanto una completa dedicaci\u00f3n a este problema deber\u00eda revisar la idiosincrasia del muestreo de barrenos, y luego sugerirse acciones correctivas. Las aplicaciones del muestreo en el control de procesos son casi ilimitadas y deber\u00eda ser el dominio de elecci\u00f3n para los fabricantes en muestreo para ofrecer sus soluciones en este congreso. La mayor\u00eda de las \u00e1reas involucradas son corrientes de procesamiento din\u00e1mico de muchas clases. El control efectivo de tales procesos involucra un entendimiento completo del proceso, el muestreo y la variabilidad de la medici\u00f3n. La cronoestad\u00edstica, una herramienta pragm\u00e1tica creada por los autores de la Teor\u00eda del Muestreo, ofrece un medio conveniente para entender tal variabilidad sin ambig\u00fcedades. Las aplicaciones de la cronoestad\u00edstica son muy amplias, desde aseguramiento de calidad, control de calidad, control de procesos, optimizaci\u00f3n de requerimientos de muestreo, descubrimiento de problemas estructurales, y muchos m\u00e1s, por tanto, una buena parte de este congreso deber\u00e1 dedicare a esta notable, simple y pragm\u00e1tica herramienta estad\u00edstica. Siempre les digo a mis clientes que ellos no sacan ventaja de todos los datos que recolectan cada d\u00eda. Hoy en d\u00eda, la industria est\u00e1 m\u00e1s y m\u00e1s preocupada en la estimaci\u00f3n de la cantidad de trazas en muchos productos. El muestreo de cantidad de trazas de impurezas o minerales raros presenta enormes dificultades te\u00f3ricas, pr\u00e1cticas y econ\u00f3micas. Sin embargo, la industria en general no est\u00e1 preparada para enfrentar estas dificultades, tal como se observa en el muestreo ambiental, el muestreo de organismos modificados gen\u00e9ticamente, muestreo de metales preciosos, muestreo de impurezas en productos farmac\u00e9uticos, muestreo de impurezas en alambres el\u00e9ctricos de cobre muy puros, etc. Es de mayor importancia el dedicar tiempo y recursos para este tema importante. Finalmente, las estimaciones de reservas minerales son una parte esencial de la econom\u00eda minera. Como consecuencia, un proceso de diligencia debida es la parte inevitable de la evaluaci\u00f3n de riesgos alcanzados por los estudios de factibilidad. Por tanto, es la misi\u00f3n de la Teor\u00eda del Muestreo abordar y ofrecer un proceso de auditor\u00eda l\u00f3gica en el muestreo para la estimaci\u00f3n de reservas minerales: este congreso sugerir\u00e1 una estrategia para este importante tema.<\/p><h4>\u00c1REAS DE INTER\u00c9S<\/h4><p>QTeor\u00eda del Muestreo.<\/p><p>Preparaci\u00f3n de muestras.<\/p><p>Mejores Pr\u00e1cticas.<\/p><p>El efecto In Situ Nugget.<\/p><p>Desarrollos y eficiencia en los Equipos para Muestreo.<\/p><p>Muestreo y Geoestad\u00edstica.<\/p><p>Muestreo en Procesamiento de Minerales.<\/p><p>Muestreo en minas a cielo abierto.<\/p><p>Muestreo en Control de Procesos.<\/p><p>Muestreo para exploraci\u00f3n y control de leyes.<\/p><p>Cronoestad\u00edstica.<\/p><p>Muestreo de cantidades de traza de impurezas.<\/p><p>Muestreo Ambiental.<\/p><p>Muestreo de metales preciosos.<\/p><p>Muestreo para estimaci\u00f3n de reservas minerales.<\/p><p>Control de Calidad.<\/p><p>Muestreo y Contabilidad Metal\u00fargica.<\/p><p>Casos de Estudio.<\/p><p>Muestreo para estudios de factibilidad de proyectos.<\/p><p>Desarrollo de est\u00e1ndares nacionales e internacionales.<\/p><p>Futuras tecnolog\u00edas.<\/p><h5>PRESIDENTE DE MUESTREO 2018 &#8211; I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES\/h2&gt;<\/h5><p>Dr. FRANCIS F. PITARD.<\/p><p>Dr. Pitard es ingeniero qu\u00edmico y doctor en tecnolog\u00edas. Con m\u00e1s de 30 a\u00f1os de experiencia t\u00e9cnica y gesti\u00f3n en la industria de los recursos naturales. Numerosas consultor\u00edas alrededor del mundo y m\u00e1s de 40 publicaciones con \u00e9nfasis en innovaci\u00f3n y rentabilidad.<\/p><p>Realiza cursos de alto nivel en prestigiosas universidades como la Colorado School of Mines, Universidad de Nevada, Universidad de Witwatersrand, entre otras. Tiene una experticia sobresaliente en todos los aspectos de la toma de muestras, las cuales ha adquirido en asociaci\u00f3n con Dr. C. O. Ingamells y Dr. Pierre M. Gy.<\/p><h4>PROGRAMA<br \/>JUEVES 25 DE OCTUBRE<\/h4><p>Palabras de bienvenida. Dr. Pitard y comit\u00e9 organizador.<\/p><h5>SESION &#8211; I<\/h5><p>Una gu\u00eda de sistemas de muestreo y protocolos de muestreo para minimizar problemas de reconciliaci\u00f3n entre ge\u00f3logos, mineros y metalurgistas. Francis Pitard. Francis Pitard Sampling Consultants. USA.<\/p><p>Beneficios de considerar una estaci\u00f3n de muestreo metal\u00fargico en norma en la etapa inicial del proyecto. Ruben Aravena Z. Rodrigo Morales D. TECPROMIN. Chile.<\/p><p>Simulaci\u00f3n de Esquema de Muestreo de Concentrados Minerales de Cobre. Omar Leva. Sociedad Minera El Brocal. Per\u00fa.<\/p><p>\u00bfQA\/QC Realidad o Fantas\u00eda? Siete a\u00f1os despues. Samuel Canchaya. Sampling OK, PER\u00da.<\/p><h5>SESION &#8211; II<\/h5><p>Impala Terminals: Pioneros en implementar tecnolog\u00eda rob\u00f3tica para el muestreo de concentrados en Per\u00fa. Cristiaan Landeo. Impala Terminals. Per\u00fa.<\/p><p>Contabilidad Metal\u00fargica. Rodrigo R. Carneiro. SGS. USA.<\/p><p>Muestreador de concentrado de cobre en sistema de recepci\u00f3n La Greda.Patricio Valenzuela. Vicente Esparza . CODELCO. Mc LANAHAN. CHILE.<\/p><h5>SESION &#8211; III<\/h5><p>Validaci\u00f3n de una nueva cortadora de banda transversal para el muestreo de minerales de oro. Ana Carolina Chieregati, Edvaldo Alves Amaral Jr., Janine Cerqueira de Oliveira Souza. Yamana Gold Inc. University of S\u00e3o Paulo. BRASIL.<\/p><p>Pr\u00e1ctica del muestreo de control de ley \u00f3ptima en la miner\u00eda a cielo abierto &#8211; Un experimento variogr\u00e1fico de comparaci\u00f3n de Blast Hole a gran escala frente a la Circulaci\u00f3n inversa. K. Engstr\u00f6m and K. Esbensen. LKAB Mining. SWEDEN.<\/p><p>Concentrador de oro por gravedad: aplicaciones, ventajas y optimizaci\u00f3n para muestras de oro desafiantes. Steve Russell, Ross Cunningham, Andrew Mowlem. Scott Automation. RockLabs. NUEVA ZELANDA.<\/p><p>Soluci\u00f3n de Muestreo de Planta de Oro para fines de Reconciliaci\u00f3n. Reinaldo Novaes. FLSmidth.<\/p><p>Sistemas de Control de Calidad. Reinaldo Novaes. FLSmidth. Brasil.<\/p><h5>SESION &#8211; IV<\/h5><p>Estimaci\u00f3n del error de fluctuaci\u00f3n de la heterogeneidad de una alimentaci\u00f3n en una planta de willemita. F. Campos, A.C. Chieregati, T. Nunan, W. Rodrigues. Votorantim Metais. BRASIL.<\/p><p>Importancia del c\u00e1lculo de la densidad, en la estimaci\u00f3n de recursos, reservas y la conciliaci\u00f3n para yacimientos p\u00f3rfidos de cobre, en mina Cuajone al sur del Per\u00fa. Juver V\u00e9lez R\u00edos, Yuri Turpo Phu\u00f1o. Southern Copper. PER\u00da.<\/p><p>Implementaci\u00f3n de un protocolo de muestreo alternativo en un concentrador UG2 t\u00edpico en Sud\u00e1frica. N. Sukha &amp; C.J. Kruger. Anglo American Platinum. Anglo American. SUD\u00c1FRICA.<\/p><p>Lo \u00faltimo en teor\u00eda del muestreo cuantitativo: Factores de liberaci\u00f3n, forma y granulom\u00e9tricos. Dominique Francois-Bongarcon. AGORATEK International Consultants Inc., CANAD\u00c1.<\/p><p>El poder universal de la Teor\u00eda del Muestreo (TOS) en la pr\u00e1ctica. Kim H. Esbensen. KHE Consulting. DINAMARCA.<\/p><p>VIERNES 26 DE OCTUBRE<\/p><h5>SESION &#8211; V<\/h5><p>El uso de m\u00e9todos duplicados, Thompson y Howarth, sobre la evaluaci\u00f3n del protocolo de muestreo, mina Cuiab\u00e1, Brasil. V. Andrade, F. Villanova, J. Canela. Anglogold Ashanti, Federal University of Minas Gerais. BRASIL.<\/p><p>Aplicaci\u00f3n de cuarteo de pulpas como etapa intermedia entre las estaciones autom\u00e1ticas de muestreo de planta y laboratorio. Jorge L. Ch\u00e1vez. JKL Mineral Dressing. PER\u00da.<\/p><p>Muestreo para el control de calidad en una instalaci\u00f3n de almacenamiento de relaves. Pablo Hinojosa. San Agustin National University. PER\u00da.<\/p><p>El desaf\u00edo de la estacionalidad de la variabilidad observada del proceso cuando se utiliza la cronoestad\u00edstica en la planta. Francis Pitard. Francis Pitard Sampling Consultants.USA.<\/p><p>El efecto nugget en la simulaci\u00f3n geoestad\u00edstica. Daisy Arroyo. Universidad de Concepci\u00f3n. CHILE.<\/p><h5>SESION &#8211; VI<\/h5><p>Caja de herramientas del software esencial de un practicante de muestreo basado en la teor\u00eda del muestreo. Maxime Pitard. HonuaTek. USA.<\/p><p>Selecci\u00f3n de muestra localizada para pruebas geometal\u00fargicas y modelamiento. Yann Camus. SGS. CANAD\u00c1.<\/p><p>La superioridad de un sistema de muestreo de cono proporcional equiprobabil\u00edstico en l\u00ednea para el balance del material y el control del proceso. Francis Pitard &amp; Rolf Steinhaus. Francis Pitard Sampling Consultants. Multotec process equipment. SUD\u00c1FRICA.<\/p><p>Fallas en los flujos?. Dominique Francois-Bongarcon. AGORATEK International Consultants Inc. CANAD\u00c1.<\/p><h5>SESION &#8211; VII<\/h5><p>Proceso total variogr\u00e1fico &#8211; y caracterizaci\u00f3n del sistema de medida a trav\u00e9s de la cadena de valor completa desde el mineral hasta el env\u00edo en LKAB, Suecia. K. Engstr\u00f6m, and K. Esbensen, K.H. LKAB Mining. SUECIA.<\/p><p>Optimizaci\u00f3n de pr\u00e1cticas de muestreo en la planta metal\u00fargica Corrego do Sitio. Marcus F\u00e9lix Magalh\u00e3es, Ana Carolina Chieregati, Vin\u00edcius Moreira Assis, Guilherme Costa Peixoto, M\u00e1rcio Salgado Pereira. Anglogold Ashanti. BRASIL.<\/p><p>Certificaci\u00f3n de la estaci\u00f3n de muestreo de acuerdo con los est\u00e1ndares de aluminio y la teor\u00eda del muestreo. Bernardo Ferreira Bandeira, Ana Carolina Chieregati, Carlos Eduardo Paraizo Borges. Minera\u00e7\u00e3o Rio do Norte. BRASIL.<\/p><p>(VIDEO CONFERENCIA) Quality Management (QM), el motor del proceso de QAQC. Oscar Dominguez. BHP Billiton Geoscience Centre of Excellence. Australia.<\/p><h5>SESION &#8211; VIII<\/h5><p>Panel de expertos. Discusi\u00f3n de las presentaciones y principales conclusiones. Francis Pitard, Kim Esbensen, Dominique Francois-Bongarcon, Carolina Chieregati, entre otros.<\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4bced42\" data-eae-slider=\"61283\" data-id=\"4bced42\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0a3fd6 elementor-widget elementor-widget-heading\" data-id=\"d0a3fd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INVERSI\u00d3N USD 300<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4b6207 elementor-widget elementor-widget-heading\" data-id=\"a4b6207\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo acceder al curso?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f3a603 elementor-widget elementor-widget-text-editor\" data-id=\"6f3a603\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paso 1:<\/strong><\/p><p>Realiza el pago Web<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b81cf2 elementor-widget elementor-widget-button\" data-id=\"5b81cf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pagolink.niubiz.com.pe\/pagoseguro\/INTERMET\/915562\/info\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-credit-card\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar USD 300<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1be8f65 elementor-widget elementor-widget-text-editor\" data-id=\"1be8f65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paso 2:<\/strong><\/p><p>Completa el formulario y adjunta tu comprobante<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c164fd0 elementor-widget elementor-widget-button\" data-id=\"c164fd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/form.jotform.com\/243266023544654\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-wpforms\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Registra tu pago<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3ae947 elementor-widget elementor-widget-text-editor\" data-id=\"e3ae947\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paso 3:<\/strong><\/p><p>Procederemos a enviarte un correo con tus accesos a nuestro Campus Virtual.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c93877d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c93877d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a4c72a elementor-widget elementor-widget-heading\" data-id=\"7a4c72a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Si tienes alguna consulta, escr\u00edbenos:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e336db elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6e336db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/wa.link\/nqku2f\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ATENCI\u00d3N AL CLIENTE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-f8ca08e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"69584\" data-id=\"f8ca08e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd8b52b\" data-eae-slider=\"61865\" data-id=\"cd8b52b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES PALABRAS DE BIENVENIDA La Teor\u00eda del Muestreo, como se presenta en los libros, no es un producto aceptable para ser usado por la industria. La mayor\u00eda de los profesionales en la industria no tienen el tiempo para dedicarse a profundidad en las sutilezas de la Teor\u00eda del Muestreo; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3316","post","type-post","status-publish","format-standard","hentry","category-cursos-digitales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES - Intermetperu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES - Intermetperu\" \/>\n<meta property=\"og:description\" content=\"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES PALABRAS DE BIENVENIDA La Teor\u00eda del Muestreo, como se presenta en los libros, no es un producto aceptable para ser usado por la industria. La mayor\u00eda de los profesionales en la industria no tienen el tiempo para dedicarse a profundidad en las sutilezas de la Teor\u00eda del Muestreo; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermetperu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-19T16:58:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T15:47:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/person\\\/6e69e73c2288d470ce4773feb0166e49\"},\"headline\":\"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES\",\"datePublished\":\"2023-07-19T16:58:37+00:00\",\"dateModified\":\"2024-11-26T15:47:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/\"},\"wordCount\":1853,\"publisher\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg\",\"articleSection\":[\"cursos-digitales\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/\",\"name\":\"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES - Intermetperu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg\",\"datePublished\":\"2023-07-19T16:58:37+00:00\",\"dateModified\":\"2024-11-26T15:47:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/#primaryimage\",\"url\":\"http:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg\",\"contentUrl\":\"http:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/cursos-digitales\\\/52-primer-congreso-internacional-de-muestreo-de-minerales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/intermetperu.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#website\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/\",\"name\":\"Intermetperu\",\"description\":\"intermeteperu\",\"publisher\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intermetperu.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#organization\",\"name\":\"Intermetperu\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/INTERMET-LOGO.png\",\"contentUrl\":\"https:\\\/\\\/intermetperu.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/INTERMET-LOGO.png\",\"width\":3508,\"height\":1188,\"caption\":\"Intermetperu\"},\"image\":{\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InterMetPeru\\\/?locale=es_LA\",\"https:\\\/\\\/www.instagram.com\\\/intermet_peru\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intermetperu.com\\\/#\\\/schema\\\/person\\\/6e69e73c2288d470ce4773feb0166e49\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/intermetperu.com\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES - Intermetperu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermetperu.com\/en\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/","og_locale":"en_US","og_type":"article","og_title":"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES - Intermetperu","og_description":"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES PALABRAS DE BIENVENIDA La Teor\u00eda del Muestreo, como se presenta en los libros, no es un producto aceptable para ser usado por la industria. La mayor\u00eda de los profesionales en la industria no tienen el tiempo para dedicarse a profundidad en las sutilezas de la Teor\u00eda del Muestreo; [&hellip;]","og_url":"https:\/\/intermetperu.com\/en\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/","og_site_name":"Intermetperu","article_publisher":"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","article_published_time":"2023-07-19T16:58:37+00:00","article_modified_time":"2024-11-26T15:47:51+00:00","og_image":[{"url":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/#article","isPartOf":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/"},"author":{"name":"admin","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49"},"headline":"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES","datePublished":"2023-07-19T16:58:37+00:00","dateModified":"2024-11-26T15:47:51+00:00","mainEntityOfPage":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/"},"wordCount":1853,"publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"image":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/#primaryimage"},"thumbnailUrl":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg","articleSection":["cursos-digitales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/","url":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/","name":"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES - Intermetperu","isPartOf":{"@id":"https:\/\/intermetperu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/#primaryimage"},"image":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/#primaryimage"},"thumbnailUrl":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg","datePublished":"2023-07-19T16:58:37+00:00","dateModified":"2024-11-26T15:47:51+00:00","breadcrumb":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/#primaryimage","url":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg","contentUrl":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/07\/optimizacion-en-plantas-de-flotacion-3-768x354.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/intermetperu.com\/cursos-digitales\/52-primer-congreso-internacional-de-muestreo-de-minerales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/intermetperu.com\/"},{"@type":"ListItem","position":2,"name":"I CONGRESO INTERNACIONAL DE MUESTREO DE MINERALES"}]},{"@type":"WebSite","@id":"https:\/\/intermetperu.com\/#website","url":"https:\/\/intermetperu.com\/","name":"Intermetperu","description":"intermeteperu","publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermetperu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/intermetperu.com\/#organization","name":"Intermetperu","url":"https:\/\/intermetperu.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/","url":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","contentUrl":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","width":3508,"height":1188,"caption":"Intermetperu"},"image":{"@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","https:\/\/www.instagram.com\/intermet_peru\/?hl=en"]},{"@type":"Person","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/intermetperu.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/3316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/comments?post=3316"}],"version-history":[{"count":0,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/3316\/revisions"}],"wp:attachment":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/media?parent=3316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/categories?post=3316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/tags?post=3316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}