{"id":625,"date":"2023-05-08T12:02:19","date_gmt":"2023-05-08T17:02:19","guid":{"rendered":"https:\/\/dev.intermetperu.com\/?p=625"},"modified":"2024-12-03T17:54:19","modified_gmt":"2024-12-03T22:54:19","slug":"diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert","status":"publish","type":"post","link":"https:\/\/intermetperu.com\/en\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/","title":{"rendered":"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"625\" class=\"elementor elementor-625\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-e5f90c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"221\" data-id=\"e5f90c7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c95580f\" data-eae-slider=\"98854\" data-id=\"c95580f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-def1da9 elementor-widget elementor-widget-text-editor\" data-id=\"def1da9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c618c5 elementor-widget elementor-widget-image\" data-id=\"1c618c5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"921\" src=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg\" class=\"attachment-full size-full wp-image-627\" alt=\"CursoDesignExpert\" srcset=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg 2000w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert-300x138.jpg 300w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert-1024x472.jpg 1024w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert-768x354.jpg 768w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert-1536x707.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-697fe76 elementor-widget elementor-widget-text-editor\" data-id=\"697fe76\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section><section><p>DESIGN-EXPERT es un software de dise\u00f1o de experimentos y optimizaci\u00f3n de procesos de uso intuitivo con caracter\u00edsticas dif\u00edciles de encontrar en otro producto de similar aplicaci\u00f3n. Tan s\u00f3lo es necesario usar el mouse para mover interactivamente las gr\u00e1ficas de contorno 2-D o fijar los factores de cada coordenada, en los gr\u00e1ficos 3-D rotatorios, para visualizar m\u00e1s f\u00e1cilmente las superficies de respuestas (RSM).<\/p><p>Herramienta indispensable para cualquier ingeniero de laboratorio \u00f3 planta que desee mejorar su proceso. El software estad\u00edstico DESIGN-EXPERT permite, con una facilidad sin comparaci\u00f3n, identificar f\u00e1cilmente los factores e interacciones que afectan significativamente las respuestas de inter\u00e9s econ\u00f3mico de la planta, como tambi\u00e9n las combinaciones factibles de implementar para maximizar la utilizaci\u00f3n de los insumos \u00f3 minimizar los costos de producci\u00f3n. DESIGN-EXPERT permite simult\u00e1neamente visualizar las regiones de operaci\u00f3n \u00f3ptima de un proceso sea este de car\u00e1cter metal\u00fargico y\/o qu\u00edmico.<\/p><p>El curso est\u00e1 orientado a profesionales y\/o t\u00e9cnicos en metalurgia y afines que se desempe\u00f1an en laboratorio \/ Planta \u00f3 como empresa proveedora.<\/p><h4>OBJETIVOS<\/h4><ul><li>Capacitar a profesionales, t\u00e9cnicos afines de la especialidad de ingenier\u00eda metal\u00fargica para que dispongan de herramientas cuantitativas del Design Expert para el control de calidad y la toma de decisiones vinculadas al tratamiento de datos de su planta concentradora.<\/li><li>Conocer las funcionalidades del programa DESIGN-EXPERT como herramienta de ayuda en la incertidumbre del an\u00e1lisis de datos existente en la planta concentradora.<\/li><li>Capacitar a los participantes para la utilizaci\u00f3n del RSM (metodolog\u00eda de Superficie de respuesta) para la optimizaci\u00f3n de variables en el proceso de la planta.<\/li><\/ul><h4>TOPICS<\/h4><h5>D\u00eda 1 (4 horas)<\/h5><h5>Introducci\u00f3n al Design Expert , Caracter\u00edsticas generales del programa, Pantallas y men\u00fas, Abrir, guardar e imprimir, Opciones gr\u00e1ficas (20 minutos).<\/h5><h5>Introducci\u00f3n a los dise\u00f1os factoriales, sus aplicaciones, Definiciones b\u00e1sicas, Representaci\u00f3n geom\u00e9trica, Ventajas de los dise\u00f1os factoriales, Aleatorizar Pruebas experimental, Tipos de Dise\u00f1o de Experimentos (30 minutos).<\/h5><ul><li>Ejercicio 01.- Dise\u00f1o de experimentos unifactorial en Evaluaci\u00f3n de pH y colector en la recuperaci\u00f3n de Pb (20 minutos).<\/li><li>Ejercicio 02.- Evaluaci\u00f3n de Flujo de Aire y temperatura en la destrucci\u00f3n del Cianuro (20 minutos).<\/li><li>Ejercicio 03.- Evaluaci\u00f3n de los efectos de tres (3) reactivos en la recuperaci\u00f3n de 4 especies valiosas (30 minutos).<\/li><li>Ejercicio 04.- evaluaci\u00f3n del dise\u00f1o factorial 22 para evaluaci\u00f3n de la emisi\u00f3n de SO2 en funci\u00f3n a la altura de emisi\u00f3n. (30 minutos).<\/li><li>Ejercicio 05.- evaluaci\u00f3n del dise\u00f1o factorial 23 para evaluar la recuperaci\u00f3n de Cu en una celda Jameson. (30 minutos).<\/li><li>Ejercicio 06.- evaluaci\u00f3n del dise\u00f1o factorial 23 para evaluar reactivos en banco de flotaci\u00f3n (30 minutos).<\/li><\/ul><h5>D\u00eda 2 (4 horas)<\/h5><h5>Dise\u00f1o Fraccionados y Plackett Burman (30 minutos).<\/h5><ul><li>Ejercicio 07.- evaluaci\u00f3n del dise\u00f1o factorial fraccionado 2n-p para evaluar 6 variables para la concentraci\u00f3n de Cu (30 minutos).<\/li><li>Ejercicio 08.- Evaluaci\u00f3n de un dise\u00f1o fraccionado de 4 variables para el proceso Merrill &amp; Crowe (30 minutos).<\/li><li>Ejercicio 09.- Dise\u00f1o fraccionado para 4 factores con 3 r\u00e9plicas, para la evaluar la contaminaci\u00f3n del SO2 (30 minutos).<\/li><li>Ejercicio 10.- Evaluaci\u00f3n de un dise\u00f1o fraccionado de 6 variables para maximizar la extracci\u00f3n de Cu (30 minutos).<\/li><li>Ejercicio 11.- Dise\u00f1o fraccionado para evaluar 8 factores para la evaluaci\u00f3n de Tostaci\u00f3n de Cu (30 minutos).<\/li><li>Ejercicio 12.- dise\u00f1o con Plackett Burman con 8 variables (30 minutos).<\/li><li>Ejercicio 13.- dise\u00f1o con Plackett Burman con 10 variables (30 minutos).<\/li><\/ul><h5>D\u00eda 3 (4 horas)<\/h5><h5>Metodologia de Superficie de Respuesta (RSM), Metodolog\u00eda Dise\u00f1o Central Compuesto (CCD) \u2013 Dise\u00f1o Box-Behnken &#8211; Dise\u00f1o hexagonal, Dise\u00f1o Pentagonal ,Dise\u00f1o Octogonal, (60 minutos).<\/h5><ul><li>Ejercicio 14.- optimizar las variables operaciones de un molino de Bolas de laboratorio aplicando la metodolog\u00eda central compuesto y box behnken (30 minutos).<\/li><li>Ejercicio 15.- Dise\u00f1o hexagonal con el objeto de optimizar las dos variables principales; Xantato Z-11 y Espumante D-250 para Recuperaci\u00f3n de Cu. (30 minutos).<\/li><li>Ejercicio 16.- Dise\u00f1o hexagonal con el objeto de optimizar las dos variables principales; Concentraci\u00f3n de disolvente y diluci\u00f3n de pulpa para evaluar rangos de lixiviaci\u00f3n. (30 minutos).<\/li><li>Ejercicio 17.- Dise\u00f1o Octogonal y Pentagonal para la tostaci\u00f3n de Cu. (30 minutos).<\/li><li>Ejercicio 18.- Dise\u00f1o hexagonal y herramienta SOLVER (MS EXCEL) ,para optimizar la templabilidad de bolas de molienda (60 minutos).<\/li><\/ul><h5>D\u00eda 4 (4 horas)<\/h5><h5>Metodologia de Mezclas y Metodolog\u00eda Taguchi (60 minutos).<\/h5><ul><li>Ejercicio 19.-Metodo de Mezclas Combinaci\u00f3n de tres resinas para la extracci\u00f3n de metales pesado en efluentes. (30 minutos).<\/li><li>Ejercicio 19.-Metodo de Mezclas Combinaci\u00f3n de tres reactivos para y mejorar la calidad de un reactivo de flotaci\u00f3n de Pb. (30 minutos).<\/li><li>Ejercicio 20.- Aplicaci\u00f3n de la metodolog\u00eda Taguchi para controlar variables con ruido , para mejorar la recuperaci\u00f3n de Zn de un concentrado (40 minutos).<\/li><\/ul><h5>Comparaci\u00f3n entre los dise\u00f1os factoriales y Metodolog\u00eda Taguchi (40 minutos).<\/h5><ul><li>Otros ejercicio de Aplicaci\u00f3n complementarios (40 minutos).<\/li><\/ul><h4>INSTRUCTOR<\/h4><h5>Ing. ERNESTO VIZCARDO CORNEJO<\/h5><p>Ingeniero Metal\u00fargico, Actualmente trabaja como Ingeniero Especialista \u2013 Aceros Chilca \/ MEPSA en el \u00c1rea de Asistencia T\u00e9cnica y es Docente de la Escuela Profesional del Ingenier\u00eda Metal\u00fargica y del Instituto de Inform\u00e1tica de la Universidad Nacional de San Agust\u00edn de Arequipa; posee el grado de Magister en Mec\u00e1nica Computacional del Instituto Balseiro \u2013 Bariloche\/Universidad de Cuyo &#8211; Argentina. Actualmente lleva una Maestr\u00eda en Ingenier\u00eda Geometalurgica en la Universidad Nacional Mayor de San Marcos.<\/p><h4>\u00a0<\/h4><p>Dicta en diferentes cursos relacionado a balances metal\u00fargicos a empresa mineras como: Sociedad Minera Cerro Verde, Southern Per\u00fa, Glencore Antapaccay, Minera Shougang, las mineras del Grupo Volcan, etc Expositor en diferentes universidades del Per\u00fa como: Universidad Nacional de Ingenier\u00eda (UNI) , Universidad Nacional de San Agust\u00edn de Arequipa (UNSA), Universidad Nacional de San Antonio del Cusco (UNSAAC), Universidad Nacional Jorge Basadre (UNJBG) y actualmente es consultor en International Metallurgical Consultants (INTERMET).<\/p><h4>\u00a0<\/h4><p>Tiene diferentes dominios en softwares metal\u00fargicos como: METSIM, MODSIM, JKSIMMET, Software Estad\u00edstico aplicado a Procesos Metal\u00fargicos como: MINITAB, Design Expert 11.0, Statistical, Statgraphics Centuri\u00f3n, Origin, certificado en software Aplicativo como: Sistemas Geogr\u00e1ficos y Geo estad\u00edsticos (ARCGIS, QGIS), Dise\u00f1o y Simulaci\u00f3n por Elementos Finitos: SOLIDWORKS, SOLIDWORKS SIMULATIONS, ANSYS, Simulaci\u00f3n Por Elementos Discretos: ROCKY DEM, E-DEM Software AC-Tek NEWTON ,Especialista en metodolog\u00edas num\u00e9ricas y M\u00e9todos Num\u00e9ricos.<\/p><h4>\u00a0<\/h4><p>Conferencista en congresos internacionales tales como: Flotaci\u00f3n 2016 \/ Conminuci\u00f3n 2017 \/ Flotaci\u00f3n 2018 \/ Conminuci\u00f3n 2019, entre otros.<\/p><\/section><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b6d8dd1\" data-eae-slider=\"45759\" data-id=\"b6d8dd1\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5345123 elementor-widget elementor-widget-heading\" data-id=\"5345123\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INVERSI\u00d3N USD 250<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-950f18e elementor-widget elementor-widget-heading\" data-id=\"950f18e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo acceder al curso?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f78bc46 elementor-widget elementor-widget-text-editor\" data-id=\"f78bc46\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paso 1:<\/strong><\/p><p>Realiza el pago Web<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dc7629 elementor-widget elementor-widget-button\" data-id=\"2dc7629\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pagolink.niubiz.com.pe\/pagoseguro\/INTERMET\/931803\/info\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-credit-card\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar USD 250<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71fb715 elementor-widget elementor-widget-text-editor\" data-id=\"71fb715\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paso 2:<\/strong><\/p><p>Completa el formulario y adjunta tu comprobante<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe194e elementor-widget elementor-widget-button\" data-id=\"2fe194e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/form.jotform.com\/243266023544654\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-wpforms\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Registra tu pago<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57c0c61 elementor-widget elementor-widget-text-editor\" data-id=\"57c0c61\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paso 3:<\/strong><\/p><p>Procederemos a enviarte un correo con tus accesos a nuestro Campus Virtual.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c596fe elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8c596fe\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6765217 elementor-widget elementor-widget-heading\" data-id=\"6765217\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Si tienes alguna consulta, escr\u00edbenos:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-941cbef elementor-align-center elementor-widget elementor-widget-button\" data-id=\"941cbef\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/wa.link\/nqku2f\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ATENCI\u00d3N AL CLIENTE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98c556d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"98c556d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf4c696 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bf4c696\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT DESIGN-EXPERT es un software de dise\u00f1o de experimentos y optimizaci\u00f3n de procesos de uso intuitivo con caracter\u00edsticas dif\u00edciles de encontrar en otro producto de similar aplicaci\u00f3n. Tan s\u00f3lo es necesario usar el mouse para mover interactivamente las gr\u00e1ficas de contorno 2-D o fijar los [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[6],"tags":[],"class_list":["post-625","post","type-post","status-publish","format-standard","hentry","category-cursos-digitales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT - Intermetperu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT - Intermetperu\" \/>\n<meta property=\"og:description\" content=\"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT DESIGN-EXPERT es un software de dise\u00f1o de experimentos y optimizaci\u00f3n de procesos de uso intuitivo con caracter\u00edsticas dif\u00edciles de encontrar en otro producto de similar aplicaci\u00f3n. Tan s\u00f3lo es necesario usar el mouse para mover interactivamente las gr\u00e1ficas de contorno 2-D o fijar los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermetperu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-08T17:02:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-03T22:54:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49\"},\"headline\":\"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT\",\"datePublished\":\"2023-05-08T17:02:19+00:00\",\"dateModified\":\"2024-12-03T22:54:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/\"},\"wordCount\":1148,\"publisher\":{\"@id\":\"https:\/\/intermetperu.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg\",\"articleSection\":[\"cursos-digitales\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/\",\"url\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/\",\"name\":\"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT - Intermetperu\",\"isPartOf\":{\"@id\":\"https:\/\/intermetperu.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg\",\"datePublished\":\"2023-05-08T17:02:19+00:00\",\"dateModified\":\"2024-12-03T22:54:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#primaryimage\",\"url\":\"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg\",\"contentUrl\":\"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/intermetperu.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intermetperu.com\/#website\",\"url\":\"https:\/\/intermetperu.com\/\",\"name\":\"Intermetperu\",\"description\":\"intermeteperu\",\"publisher\":{\"@id\":\"https:\/\/intermetperu.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intermetperu.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intermetperu.com\/#organization\",\"name\":\"Intermetperu\",\"url\":\"https:\/\/intermetperu.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png\",\"contentUrl\":\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png\",\"width\":3508,\"height\":1188,\"caption\":\"Intermetperu\"},\"image\":{\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA\",\"https:\/\/www.instagram.com\/intermet_peru\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/intermetperu.com\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT - Intermetperu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermetperu.com\/en\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/","og_locale":"en_US","og_type":"article","og_title":"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT - Intermetperu","og_description":"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT DESIGN-EXPERT es un software de dise\u00f1o de experimentos y optimizaci\u00f3n de procesos de uso intuitivo con caracter\u00edsticas dif\u00edciles de encontrar en otro producto de similar aplicaci\u00f3n. Tan s\u00f3lo es necesario usar el mouse para mover interactivamente las gr\u00e1ficas de contorno 2-D o fijar los [&hellip;]","og_url":"https:\/\/intermetperu.com\/en\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/","og_site_name":"Intermetperu","article_publisher":"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","article_published_time":"2023-05-08T17:02:19+00:00","article_modified_time":"2024-12-03T22:54:19+00:00","og_image":[{"url":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#article","isPartOf":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/"},"author":{"name":"admin","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49"},"headline":"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT","datePublished":"2023-05-08T17:02:19+00:00","dateModified":"2024-12-03T22:54:19+00:00","mainEntityOfPage":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/"},"wordCount":1148,"publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"image":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#primaryimage"},"thumbnailUrl":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg","articleSection":["cursos-digitales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/","url":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/","name":"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT - Intermetperu","isPartOf":{"@id":"https:\/\/intermetperu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#primaryimage"},"image":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#primaryimage"},"thumbnailUrl":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg","datePublished":"2023-05-08T17:02:19+00:00","dateModified":"2024-12-03T22:54:19+00:00","breadcrumb":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#primaryimage","url":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg","contentUrl":"http:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/CursoDesignExpert.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/intermetperu.com\/cursos-digitales\/diseno-de-experimentos-y-optimizacion-en-procesamiento-de-minerales-con-design-expert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/intermetperu.com\/"},{"@type":"ListItem","position":2,"name":"DISE\u00d1O DE EXPERIMENTOS Y OPTIMIZACI\u00d3N EN PROCESAMIENTO DE MINERALES CON DESIGN-EXPERT"}]},{"@type":"WebSite","@id":"https:\/\/intermetperu.com\/#website","url":"https:\/\/intermetperu.com\/","name":"Intermetperu","description":"intermeteperu","publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermetperu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/intermetperu.com\/#organization","name":"Intermetperu","url":"https:\/\/intermetperu.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/","url":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","contentUrl":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","width":3508,"height":1188,"caption":"Intermetperu"},"image":{"@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","https:\/\/www.instagram.com\/intermet_peru\/?hl=en"]},{"@type":"Person","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/intermetperu.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/comments?post=625"}],"version-history":[{"count":0,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/625\/revisions"}],"wp:attachment":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/media?parent=625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/categories?post=625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/tags?post=625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}