{"id":688,"date":"2023-05-09T09:44:13","date_gmt":"2023-05-09T14:44:13","guid":{"rendered":"https:\/\/dev.intermetperu.com\/?p=688"},"modified":"2023-05-26T11:35:54","modified_gmt":"2023-05-26T16:35:54","slug":"control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital","status":"publish","type":"post","link":"https:\/\/intermetperu.com\/en\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/","title":{"rendered":"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"688\" class=\"elementor elementor-688\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-e5f90c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"68533\" data-id=\"e5f90c7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-c95580f\" data-eae-slider=\"13983\" data-id=\"c95580f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-def1da9 elementor-widget elementor-widget-text-editor\" data-id=\"def1da9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"box-sizing: border-box; font-family: Oswald, Arial, sans-serif; font-size: 20px; color: #0c4e94; margin: 0px 0px 20px; padding: 0px; border: 0px; outline: 0px; font-weight: normal; font-style: normal; vertical-align: baseline; line-height: normal; letter-spacing: 0.01em; font-variant-ligatures: normal; font-variant-caps: normal; orphans: 2; text-align: left; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial;\">CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c618c5 elementor-widget elementor-widget-image\" data-id=\"1c618c5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"922\" src=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg\" class=\"attachment-full size-full wp-image-690\" alt=\"curso-control-de-procesos\" srcset=\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg 2000w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos-300x138.jpg 300w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos-1024x472.jpg 1024w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos-768x354.jpg 768w, https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos-1536x708.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-697fe76 elementor-widget elementor-widget-text-editor\" data-id=\"697fe76\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>OBJETIVOS<\/p><h5>www.osbdigit.com<\/h5><p>Ahora m\u00e1s que nunca la estrategia de trabajo remoto con soporte en el desarrollo de nuevas formas de creaci\u00f3n de valor en la gesti\u00f3n operacional es vital.<\/p><p>La creaci\u00f3n de modelos predictivos para evitar p\u00e9rdidas de producci\u00f3n, energ\u00eda, agua y contaminaci\u00f3n ambiental.<\/p><p>Trabajar en forma remota con un coach que ayuda a crear an\u00e1lisis operacional en tiempo real, con alertas oportunas al acercarse a restricciones o salirse de las bandas de producci\u00f3n optima contenidas en la historia de la producci\u00f3n efectiva.<\/p><p>Renovar y mantener los lazos de control de procesos para poder ejecutar autom\u00e1ticamente los planes de producci\u00f3n sincronizando la mina y las operaciones.<\/p><h4>TOPICS<\/h4><h5>D\u00cdA 1<\/h5><p>1.\u00a0Introducci\u00f3n (10 minutos)<\/p><p>2.\u00a0Fundamentos de Control de Procesos (120 minutos)<\/p><ul><li>\u00bfPor qu\u00e9 necesitamos controles?.<\/li><li>Los lazos de control de procesos.<\/li><li>Documentaci\u00f3n de control de procesos.<\/li><\/ul><p>3.\u00a0Mediciones en los procesos<\/p><ul><li>Sistemas de muestreo<\/li><li>Analizadores online especializados.<\/li><li>Softsensors.<\/li><li>Instrumentaci\u00f3n, dispositivos y redes.<\/li><\/ul><p>4.\u00a0Estrategias de control de Procesos (120 minutos)<\/p><ul><li style=\"list-style-type: none;\"><ul><li>Tabla del conocimiento de operaciones para el procesamiento de minerales.<\/li><li>Algoritmos de control de proceso.<\/li><\/ul><\/li><\/ul><p>Controles de regulaci\u00f3n primaria.<\/p><p>Controles de proceso multivariable.<\/p><p>Coordinaci\u00f3n hol\u00edstica de procesos integrados.<\/p><h5>D\u00cdA 2<\/h5><p>Ejemplos de control de procesos.<\/p><p>Ejemplos en procesamiento de minerales:<\/p><p>&#8211; Controlador de Control Predictivo por Modelo (MPC, por sus siglas en ingl\u00e9s) del Circuito de Molino de Bolas y Molino SAG.<\/p><p>&#8211; Controles de circuitos Rougher y Scavenger de flotaci\u00f3n de cobre.<\/p><p>&#8211; Controlador multivariable del espesamiento.<\/p><p>Ejemplo en hidrometalurgia:<\/p><p>&#8211; Implementaci\u00f3n del MPC en Lixiviaci\u00f3n cianurada de oro.<\/p><p>Ejemplo en pirometalurgia:<\/p><p>&#8211; Controles integrados del horno de arco el\u00e9ctrico para ferron\u00edquel.<\/p><p>5.\u00a0Gesti\u00f3n de operacional din\u00e1mica de las plantas en una empresa (140 minutos)<\/p><ul><li>Monitoreo de gesti\u00f3n operacional en colaboraci\u00f3n de todas las funciones.<\/li><li>Planeamiento integrado e inteligencia operacional de producci\u00f3n.<\/li><li>Monitoreo de los equipos cr\u00edticos usando modelos predictivos.<\/li><li>Monitoreo de la calidad de los lazos de control de procesos y los actuadores mec\u00e1nicos.<\/li><li>Integraci\u00f3n de las Minas, Transporte del Mineral, Plantas de Procesamiento y Despachos.<\/li><li>Optimizaci\u00f3n de la cadena de suministro de hierro: de la planta al puerto.<\/li><li>Optimizaci\u00f3n de la recuperaci\u00f3n de oro y cobre.<\/li><li>Optimizaci\u00f3n de la recuperaci\u00f3n de n\u00edquel y cobre.<\/li><li>Miner\u00eda empresarial, gesti\u00f3n de energ\u00eda del procesamiento de minerales y metalurgia extractiva.<\/li><li>Centros de competencia de monitoreo de la producci\u00f3n de concentrados.<\/li><li>Monitoreo y diagn\u00f3stico de generaci\u00f3n de energ\u00eda empresarial.<\/li><li>Balances de masa y reconciliaci\u00f3n de datos.<\/li><\/ul><h5>D\u00cdA 3<\/h5><p>6.\u00a0Internet industrial de las cosas, disrupci\u00f3n digital en automatizaci\u00f3n (60 minutos)<\/p><ul><li>Equipo remoto y soporte en la optimizaci\u00f3n de recuperaci\u00f3n de proceso.<\/li><li>Control de procesos y gesti\u00f3n operacional empresarial en la Era Digital.<\/li><li>Preparando a las computadoras a trabajar con personas en las plantas y centros de competencias.<\/li><li>Nuevos beneficios en la Era Digital.<\/li><\/ul><p>7.\u00a0Ejemplos en vivo de Plantas de Procesamiento de Minerales y Metalurgia Extractiva (120 minutos)<\/p><ul><li>Transformaci\u00f3n de los datos a una Planta de Procesamiento Digital usando los sistemas PI y otros historiadores con Seeq y PowerBI.<\/li><li>Dynamill II, Simulaci\u00f3n de Proceso Din\u00e1mico para Alternativas de Control de Proceso.<\/li><li>Dynaflote, Modelo de Simulaci\u00f3n de Flotaci\u00f3n Din\u00e1mica para Alternativas de Control.<\/li><li>DynaThick, Modelo Din\u00e1mico de Espesadores para la identificaci\u00f3n online de su inventario.<\/li><li>Optimill, Modelo de Diagn\u00f3stico de circuito de molienda para buscar el tonelaje \u00f3ptimo de la operaci\u00f3n.<\/li><li>Se les mostrar\u00e1 en un ambiente PI en ejemplo completo de dise\u00f1o de la fuente de datos y en Seeq Advanced Analytics\/Modelaje y PowerBI (Gestion Operacional y Inteligencia Artificial) c\u00f3mo se transforman los datos en informaci\u00f3n.<\/li><\/ul><p>8.\u00a0Modelo de Gesti\u00f3n Operacional de las Plantas de los participantes (60 minutos)<\/p><ul><li>Presentaciones de los Participantes 10 Minutos por Participante.<\/li><li>Preguntas y Respuestas.<\/li><li>Conclusiones.<\/li><\/ul><h4>INSTRUCTOR<\/h4><h5>Dr. OSVALDO BASCUR<\/h5><p>La carrera del Dr. Bascur abarca m\u00e1s de 30 a\u00f1os de meritorias contribuciones cient\u00edficas y de ingenier\u00eda seminal para la comprensi\u00f3n de la tecnolog\u00eda de procesamiento de minerales en las \u00e1reas de trituraci\u00f3n, clasificaci\u00f3n, flotaci\u00f3n por espuma, espesamiento e hidrometalurgia. Ha sido l\u00edder en la implementaci\u00f3n industrial de modelado, an\u00e1lisis y optimizaci\u00f3n de procesos din\u00e1micos de operaciones de procesamiento de minerales. Sus contribuciones destacadas se basan en m\u00e1s de 10 a\u00f1os de investigaci\u00f3n fundamental fundamental y 20 a\u00f1os de ser pionero en el comportamiento transformacional industrial utilizando el control de procesos y la gesti\u00f3n operativa de la informaci\u00f3n en tiempo real. La mejora continua y la innovaci\u00f3n resultante de la miner\u00eda y los complejos de procesamiento de minerales para la reducci\u00f3n de costos operativos se han difundido ampliamente en m\u00e1s de 100 art\u00edculos t\u00e9cnicos, y en numerosas presentaciones cient\u00edficas y de la industria en todos los continentes. Dr. Bascur es el creador de laModelos industriales de simulaci\u00f3n din\u00e1mica Dynafloat \u00a9 y Dynamill \u00a9 . Recientemente ha dise\u00f1ado un algoritmo que caracteriza las condiciones de operaci\u00f3n de una planta industrial para evaluar el desempe\u00f1o operativo de cada \u00e1rea de la planta. La clasificaci\u00f3n de los datos operativos permite la generaci\u00f3n de modelos predictivos utilizando herramientas de aprendizaje autom\u00e1tico para la optimizaci\u00f3n minera \/ molino \/ metal\u00fargica. Se logran grandes ahorros de costos con una captura autom\u00e1tica de peque\u00f1os retrasos en la producci\u00f3n de equipos y la estimaci\u00f3n de p\u00e9rdidas de agua se implementan en grandes complejos industriales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c3912fb\" data-eae-slider=\"10102\" data-id=\"c3912fb\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9bfe3e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c9bfe3e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pagolink.niubiz.com.pe\/pagoseguro\/INTERMET\/931824\/info\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1 PAGAR AHORA !<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9048dd elementor-widget elementor-widget-text-editor\" data-id=\"f9048dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><b>PRECIO : US$400<\/b><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc1e5f9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fc1e5f9\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55f07f9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"55f07f9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/intermetperu.com\/cursos-digitales\/index.php\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver a P\u00e1gina de Inicio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-110cee0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"110cee0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5c24ce elementor-widget elementor-widget-heading\" data-id=\"e5c24ce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 class=\"tituloblanco\" style=\"font-family: Oswald, Arial, sans-serif;font-size: 16px;margin: 6px;letter-spacing: 0.01em;white-space: normal\"><b>CONSULTA SOBRE ESTE CURSO<\/b><\/h2><p class=\"txtblanco\" style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px;white-space: normal\">No dude en comunicarce con nosotros y de inmediato lo vamos a guiar en todo lo necesario.<\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><textarea name=\"comentarios\" id=\"comentarios\" class=\"comentarios\" style=\"width: 242.135px;height: 100px;padding: 20px;border-width: 2px;border-radius: 0.25rem\"><\/textarea><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\"><\/p><p style=\"font-family: ArchivoNarrowregular, Arial, sans-serif;font-size: 15px;margin: 6px\">NOTA : Los campos que poseen (*) son considerados obligatorios.<\/p><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-f8ca08e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"93650\" data-id=\"f8ca08e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd8b52b\" data-eae-slider=\"72663\" data-id=\"cd8b52b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL OBJETIVOS www.osbdigit.com Ahora m\u00e1s que nunca la estrategia de trabajo remoto con soporte en el desarrollo de nuevas formas de creaci\u00f3n de valor en la gesti\u00f3n operacional es vital. La creaci\u00f3n de modelos predictivos para evitar p\u00e9rdidas de producci\u00f3n, energ\u00eda, agua y [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[6],"tags":[],"class_list":["post-688","post","type-post","status-publish","format-standard","hentry","category-cursos-digitales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL - Intermetperu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL - Intermetperu\" \/>\n<meta property=\"og:description\" content=\"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL OBJETIVOS www.osbdigit.com Ahora m\u00e1s que nunca la estrategia de trabajo remoto con soporte en el desarrollo de nuevas formas de creaci\u00f3n de valor en la gesti\u00f3n operacional es vital. La creaci\u00f3n de modelos predictivos para evitar p\u00e9rdidas de producci\u00f3n, energ\u00eda, agua y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermetperu.com\/en\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermetperu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-09T14:44:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-26T16:35:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49\"},\"headline\":\"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL\",\"datePublished\":\"2023-05-09T14:44:13+00:00\",\"dateModified\":\"2023-05-26T16:35:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/\"},\"wordCount\":1004,\"publisher\":{\"@id\":\"https:\/\/intermetperu.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg\",\"articleSection\":[\"cursos-digitales\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/\",\"url\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/\",\"name\":\"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL - Intermetperu\",\"isPartOf\":{\"@id\":\"https:\/\/intermetperu.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg\",\"datePublished\":\"2023-05-09T14:44:13+00:00\",\"dateModified\":\"2023-05-26T16:35:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#primaryimage\",\"url\":\"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg\",\"contentUrl\":\"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/intermetperu.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intermetperu.com\/#website\",\"url\":\"https:\/\/intermetperu.com\/\",\"name\":\"Intermetperu\",\"description\":\"intermeteperu\",\"publisher\":{\"@id\":\"https:\/\/intermetperu.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intermetperu.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intermetperu.com\/#organization\",\"name\":\"Intermetperu\",\"url\":\"https:\/\/intermetperu.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png\",\"contentUrl\":\"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png\",\"width\":3508,\"height\":1188,\"caption\":\"Intermetperu\"},\"image\":{\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA\",\"https:\/\/www.instagram.com\/intermet_peru\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/intermetperu.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/intermetperu.com\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL - Intermetperu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermetperu.com\/en\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/","og_locale":"en_US","og_type":"article","og_title":"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL - Intermetperu","og_description":"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL OBJETIVOS www.osbdigit.com Ahora m\u00e1s que nunca la estrategia de trabajo remoto con soporte en el desarrollo de nuevas formas de creaci\u00f3n de valor en la gesti\u00f3n operacional es vital. La creaci\u00f3n de modelos predictivos para evitar p\u00e9rdidas de producci\u00f3n, energ\u00eda, agua y [&hellip;]","og_url":"https:\/\/intermetperu.com\/en\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/","og_site_name":"Intermetperu","article_publisher":"https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","article_published_time":"2023-05-09T14:44:13+00:00","article_modified_time":"2023-05-26T16:35:54+00:00","og_image":[{"url":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#article","isPartOf":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/"},"author":{"name":"admin","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49"},"headline":"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL","datePublished":"2023-05-09T14:44:13+00:00","dateModified":"2023-05-26T16:35:54+00:00","mainEntityOfPage":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/"},"wordCount":1004,"publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"image":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#primaryimage"},"thumbnailUrl":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg","articleSection":["cursos-digitales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/","url":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/","name":"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL - Intermetperu","isPartOf":{"@id":"https:\/\/intermetperu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#primaryimage"},"image":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#primaryimage"},"thumbnailUrl":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg","datePublished":"2023-05-09T14:44:13+00:00","dateModified":"2023-05-26T16:35:54+00:00","breadcrumb":{"@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#primaryimage","url":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg","contentUrl":"http:\/\/dev.intermetperu.com\/wp-content\/uploads\/2023\/05\/curso-control-de-procesos.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/intermetperu.com\/cursos-digitales\/control-de-procesos-y-gestion-operacional-dinamica-de-plantas-en-la-era-digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/intermetperu.com\/"},{"@type":"ListItem","position":2,"name":"CONTROL DE PROCESOS Y GESTI\u00d3N OPERACIONAL DIN\u00c1MICA DE PLANTAS EN LA ERA DIGITAL"}]},{"@type":"WebSite","@id":"https:\/\/intermetperu.com\/#website","url":"https:\/\/intermetperu.com\/","name":"Intermetperu","description":"intermeteperu","publisher":{"@id":"https:\/\/intermetperu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermetperu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/intermetperu.com\/#organization","name":"Intermetperu","url":"https:\/\/intermetperu.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/","url":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","contentUrl":"https:\/\/intermetperu.com\/wp-content\/uploads\/2023\/05\/INTERMET-LOGO.png","width":3508,"height":1188,"caption":"Intermetperu"},"image":{"@id":"https:\/\/intermetperu.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InterMetPeru\/?locale=es_LA","https:\/\/www.instagram.com\/intermet_peru\/?hl=en"]},{"@type":"Person","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/6e69e73c2288d470ce4773feb0166e49","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/intermetperu.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99b67d6ed17930129be722235b5a107be1e3eb1771892c81b50da7524668ceb8?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/intermetperu.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/comments?post=688"}],"version-history":[{"count":0,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/posts\/688\/revisions"}],"wp:attachment":[{"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/media?parent=688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/categories?post=688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intermetperu.com\/en\/wp-json\/wp\/v2\/tags?post=688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}